{"id":3,"date":"2023-08-16T23:57:11","date_gmt":"2023-08-16T21:57:11","guid":{"rendered":"https:\/\/menofwrestling.com\/?page_id=3"},"modified":"2023-08-18T19:20:20","modified_gmt":"2023-08-18T17:20:20","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/menofwrestling.com\/es\/privacy-policy\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"<div class=\"aex-box-content\">\n<h2 data-aos=\"zoom-in\" data-aos-duration=\"1800\">\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung.<\/h2>\n<p>Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere \u00fcber Art, Umfang, Zweck, Dauer und Rechtsgrundlage der Verarbeitung personenbezogener Daten, soweit \u00abMen of Wrestling\u00bb allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung entscheidet.<\/p>\n<p>\tWenn du nun die Website von \u00abMen of Wrestling\u00bb besuchst bzw. nutzt, werden (unter Umst\u00e4nden) verschiedene personenbezogene Daten (im Nachfolgenden \u00abDaten\u00bb) erhoben. Personenbezogene Daten sind Daten, mit denen du pers\u00f6nlich identifiziert werden kannst.<\/p>\n<p>\tDiese vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert zudem, welche Daten \u00abMen of Wrestling\u00bb erhebt und wof\u00fcr diese genutzt werden. Sie erl\u00e4utert auch, wie und zu welchem Zweck dies geschieht?<\/p>\n<p>\t\u00abMen of Wrestling\u00bb m\u00f6chte dich dar\u00fcber in Kenntnis setzen, dass zu keiner Zeit von dir erhobenen personenbezogenen Daten seitens \u00abMen of Wrestling\u00bb an Dienstleister f\u00fcr Werbezwecke verliehen, verschenkt oder gar verkauft werden!<\/p>\n<p>\tZudem m\u00f6chte \u00abMen of Wrestling\u00bb besonders betonen, dass auf diesen Seiten keine Social-Plugins von Facebook (\u00abGef\u00e4llt mir\u00bb- oder \u00abTeilen\u00bb-Buttons) implementiert sind, damit dein Besuch dieser Website von \u00abMen of Wrestling\u00bb seitens Facebook und Google (gleichg\u00fcltig ob du ein Account bei Facebook oder Google hast oder nicht), nicht direkt oder indirekt mittels dieser Social-Plugins getrackt werden k\u00f6nnen!<\/p>\n<p>\t\u00abMen of Wrestling\u00bb m\u00f6chte dich zudem darauf hinweisen, dass die generelle Daten\u00fcbertragung im Internet (zum Beispiel bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich, daher kann \u00abMen of Wrestling\u00bb einen l\u00fcckenlosen Schutz nicht garantieren. Um dir jedoch die gr\u00f6sstm\u00f6glichste Datensicherheit bieten zu k\u00f6nnen, nutzt \u00abMen of Wrestling\u00bb aus Gr\u00fcnden der Sicherheit und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel der Anfragen, die du an \u00abMen of Wrestling\u00bb sendest, eine sichere SSL-Verschl\u00fcsselung.<\/p>\n<p>\tDes Weiteren nimmt \u00abMen of Wrestling\u00bb unter Umst\u00e4nden f\u00fcr einzelne Funktionen die Dienste von externen Anbietern, wie beispielsweise Google oder PayPal in Anspruch. \u00dcber die jeweiligen Vorg\u00e4nge m\u00f6chte dich \u00abMen of Wrestling\u00bb ebenfalls im Folgenden mit dieser Datenschutzerkl\u00e4rung informieren und aufkl\u00e4ren.<\/p>\n<p>\tIm Hinblick auf die verwendeten Begriffe, wie zum Beispiel \u00abVerarbeitung\u00bb oder \u00abVerantwortlicher\u00bb verweist \u00abMen of Wrestling\u00bb auf die Definitionen im Artikel 4 der Datenschutzgrundverordnung (DSGVO).<\/p>\n<p>\tGem\u00e4ss Artikel 4 Ziffer 1. der Verordnung (E.U.) 2016\/679, also der Datenschutzgrundverordnung (nachfolgend nur \u00abDSGVO\u00bb genannt), gilt als \u00abVerarbeitung\u00bb jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrter Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten, wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/p>\n<p>\tZudem informiert dich \u00abMen of Wrestling\u00bb nachfolgend \u00fcber die von ihm zu Optimierungszwecken sowie zur Steigerung der Nutzungsqualit\u00e4t eingesetzten Fremdkomponenten, soweit hierdurch Dritte personenbezogene Daten in wiederum eigener Verantwortung verarbeiten.<\/p>\n<div class=\"blank150\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">00. | Gliederung dieser Datenschutzerkl\u00e4rung<\/h3>\n<p>Diese Datenschutzerkl\u00e4rung ist wie folgt gegliedert:<\/p>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">01. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#responsibility\" target=\"_self\">Verantwortlicher dieser Website und dieses Projekts<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">02. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#user-rights\" target=\"_self\">Rechte der Nutzer und Betroffenen<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">03. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#data\" target=\"_self\">Informationen zur Datenverarbeitung<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">04. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#ccpa\" target=\"_self\">California Consumer Privacy Act<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">05. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#cookies\" target=\"_self\">Cookies<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">06. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#vertrag\" target=\"_self\">Vertragsabwicklung<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">07. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#account\" target=\"_self\">Registrierung, Account und K\u00fcndigung<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">08. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#newsletter\" target=\"_self\">Newsletter<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">09. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#contact\" target=\"_self\">Kontakt<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">10. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#comments\" target=\"_self\">Nutzerbeitr\u00e4ge, Kommentare und Bewertungen<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">11. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#abonnement\" target=\"_self\">Abonnieren von Beitr\u00e4gen<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">12. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#google-adsense\" target=\"_self\">Google Ads<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">13. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#google-ads\" target=\"_self\">Google Ads mit Conversion-Tracking (Google AdWords)<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">14. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#google-analytics\" target=\"_self\">Google Analytics<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">15. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#google-fonts\" target=\"_self\">Fonts von Google und Adobe<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">16. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#google-maps\" target=\"_self\">Google Maps<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">17. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#google-recaptcha\" target=\"_self\">Google ReCaptcha<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">18. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#google-remarketing\" target=\"_self\">Google Remarketing, Google Doubleclick oder \u00ab\u00c4hnliche Zielgruppen\u00bb-Komponente von Google<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">19. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#youtube\" target=\"_self\">YouTube<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">20. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#social-media\" target=\"_self\">Social Media<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">21. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#social-plugins\" target=\"_self\">Social Plugins<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">22. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#shariff\" target=\"_self\">Datenschutzkonforme Social Media-Buttons: \u00abShariff\u00bb-Buttons\u00bb<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">23. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#likes\" target=\"_self\">Die \u00abLike\u00bb-Funktion<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">24. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#sweepstakes\" target=\"_self\">Gewinnspiele<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-left\">25. | <\/div>\n<div class=\"aex-imprint-table-right\"><a class=\"aex-imprint-link-title\" href=\"#cloudfare\" target=\"_self\">Cloudfare<\/a><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"responsibility\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">01. | Verantwortlicher dieser Website und dieses Projekts<\/h3>\n<p>\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb ist ein Projekt von<\/p>\n<div class=\"aex-box\">\n<div class=\"blank40\"><\/div>\n<p>\t\t\t<a href=\"https:\/\/aexraex.com\/de\/\" target=\"_blank\" title=\"Aexraex | The Pioneer \u2022 Digital Content Creation\"><img decoding=\"async\" class=\"aex-imprint-logo-aexraex\" data-aos=\"flip-right\" data-aos-duration=\"2500\" src=\"https:\/\/menofwrestling.com\/com\/images\/logos\/logo001-aexraex-digital-content-creation-black.png\" alt=\"Aexraex | The Pioneer \u2022 Digital Content Creation\"><\/a>\n\t\t<\/div>\n<div class=\"aex-box\">\n\t\t\tAexraex | The Pioneer<br \/>\n\t\t\tDigital Content Creation\n\t\t<\/div>\n<div class=\"blank70\"><\/div>\n<div class=\"aex-box\">\n\t\t\t<a href=\"https:\/\/menofwrestling.com\/de\/\" target=\"_self\" title=\"Men of Wrestling | Turkish Oil Wrestling\"><img decoding=\"async\" class=\"aex-imprint-logo-aexraex\" data-aos=\"flip-right\" data-aos-duration=\"2500\" src=\"https:\/\/menofwrestling.com\/com\/images\/logos\/logo001-men-wof-wrestling-turkish-oil-wrestling.png\" alt=\"Men of Wrestling | Turkish Oil Wrestling\"><\/a>\n\t\t<\/div>\n<div class=\"aex-box\">\n\t\t\tMen of Wrestling<br \/>\n\t\t\tTurkish Oil Wrestling<\/p>\n<div class=\"blank50\"><\/div>\n<p>\t\t\tAttila Cavus<br \/>\n\t\t\tPostfach 10 13 15<br \/>\n\t\t\t40004 D\u00fcsseldorf<br \/>\n\t\t\tDeutschland<br \/>\n\t\t\tEurop\u00e4ische Union\n\t\t<\/p><\/div>\n<p>\t\t<strong>Offizielle Website<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/\" target=\"_self\">menofwrestling.com<\/a><\/p>\n<p>\t\t<strong>Impressum<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/imprint\/\" target=\"_self\">menofwrestling.com\/de\/imprint\/<\/a><\/p>\n<p>\t\t<strong>Datenschutzerkl\u00e4rung<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/privacy-policy\/\" target=\"_self\">menofwrestling.com\/de\/privacy-policy\/<\/a><\/p>\n<p>\t\t<strong>Nutzungsbedingungen<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/terms-of-use\/\" target=\"_self\">menofwrestling.com\/de\/terms-of-use\/<\/a><\/p>\n<p>\t\t<strong>Ressourcen<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/resources\/\" target=\"_self\">menofwrestling.com\/de\/resources\/<\/a><\/p>\n<p>\t\t<strong>Ressourcen | Photographen und Athleten<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/resources-photographers-and-athletes\/\" target=\"_self\">menofwrestling.com\/de\/resources-photographers-and-athletes\/<\/a><\/p>\n<p>\t\t<strong>E-Mail<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"mailto:info@menofwrestling.com\">info@menofwrestling.com<\/a><\/p>\n<p>\t\t<strong>Kontakt<\/strong><br \/>\n\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/contact\/\" target=\"_self\">Kontaktformular<\/a><\/p>\n<div class=\"blank100\"><\/div>\n<p>Umsatzsteuer-Identifikationsnummer gem\u00e4ss \u00a727a Umsatzsteuergesetz:<br \/>\n\t\tUStG 106\/5050\/4660<\/p>\n<p>\t\tKein Umsatzsteuerausweis aufgrund Anwendung der Kleinunternehmerregelung gem\u00e4ss \u00a719 Umsatzsteuergesetz.<\/p>\n<p>\t\tAngaben gem\u00e4ss \u00a75 TMG und Verantwortlicher dieser Website und dieses Projekts ist<br \/>\n\t\tAttila Cavus<\/p>\n<p>\t\tDas Eleven Network besteht aus (non-)kommerziellen Projekten, die von Attila Cavus als Privatperson bzw. \u00abAexraex | The Pioneer\u00bb konzipiert, realisiert und betreut werden. Der Betreiber deklariert \u00abMen of Wrestling\u00bb als nonkommerzielles Projekt, weil keine Gewinnabsichten hinter diesem Projekt stecken. Unter Umst\u00e4nden k\u00f6nnen an gewissen Stellen Banner von Google Ads platziert sein, um die Kosten f\u00fcr das Betreiben dieses Projekts, der Domain und des Servers decken zu k\u00f6nnen.<\/p>\n<p>\t\tFalls du \u00abMen of Wrestling\u00bb interessant findest und von diesem Projekt begeistert bist, kannst du gerne dieses Projekt auch finanziell unterst\u00fctzen. Per PayPal kannst du gerne deine Spende an folgende Adresse senden: <a class=\"aex-imprint-links\" href=\"mailto:info@menofwrestling.com\">info@menofwrestling.com<\/a><\/p>\n<p>\t\t\u00abMen of Wrestling\u00bb m\u00f6chte sich bei allen Athleten dieses Projekts, Fans und Usern, Photographen, Fanbeauftragten, Vereinen, Bild- und Sportagenturen herzlichst f\u00fcr die gute Zusammenarbeit bedanken.<\/p>\n<p>\t\tDanke!<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"user-rights\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">02. | Rechte der Nutzer und Betroffenen<\/h3>\n<p>Mit Blick auf die nachfolgend noch n\u00e4her beschriebene Datenverarbeitung haben die Nutzer und Betroffenen das Recht<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">auf Best\u00e4tigung, ob betreffende Daten verarbeitet werden, auf Auskunft \u00fcber die verarbeiteten Daten, auf weitere Informationen \u00fcber die Datenverarbeitung sowie auf Kopien der Daten (vgl. auch Artikel 15 DSGVO),<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">auf Berichtigung oder Vervollst\u00e4ndigung unrichtiger bzw. unvollst\u00e4ndiger Daten (vgl. auch Artikel 16 DSGVO),<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">auf unverz\u00fcgliche L\u00f6schung der sie betreffenden Daten (vgl. auch Artikel 17 DSGVO), oder, alternativ, soweit eine weitere Verarbeitung gem\u00e4ss Artikel 17 Absatz 3 DSGVO erforderlich ist, auf Einschr\u00e4nkung der Verarbeitung nach Massgabe von Artikel 18 DSGVO,<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">auf Erhalt der sie betreffenden und von ihnen bereitgestellten Daten und auf \u00dcbermittlung dieser Daten an andere Anbieter\/Verantwortliche (vgl. auch Artikel 20 DSGVO),<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">auf Beschwerde gegen\u00fcber der Aufsichtsbeh\u00f6rde, sofern diese der Ansicht sind, dass die sie betreffenden Daten durch den Anbieter unter Verstoss gegen datenschutzrechtliche Bestimmungen verarbeitet werden (vgl. auch Artikel 77 DSGVO).<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank30\"><\/div>\n<p>Dar\u00fcber hinaus ist der Betreiber dieser Website dazu verpflichtet, alle Empf\u00e4nger, denen gegen\u00fcber Daten durch ihn offengelegt worden sind, \u00fcber jedwede Berichtigung oder L\u00f6schung von Daten oder die Einschr\u00e4nkung der Verarbeitung, die aufgrund der Artikel 16, 17 Abs\u00e4tze 1, 18 DSGVO erfolgt, zu unterrichten. Diese Verpflichtung besteht jedoch nicht, soweit diese Mitteilung unm\u00f6glich oder mit einem unverh\u00e4ltnism\u00e4ssigen Aufwand verbunden ist. Unbeschadet dessen hat der Nutzer ein Recht auf Auskunft \u00fcber diese Empf\u00e4nger.<\/p>\n<p>\t\tEbenfalls haben die Nutzer und Betroffenen nach Artikel 21 DSGVO das Recht auf Widerspruch gegen die k\u00fcnftige Verarbeitung der sie betreffenden Daten, sofern die Daten durch den Anbieter nach Massgabe von Artikel 6 Absatz 1 lit. f) DSGVO verarbeitet werden. Insbesondere ist ein Widerspruch gegen die Datenverarbeitung zum Zwecke der Direktwerbung statthaft.<\/p>\n<p>\t\tDurch deine Teilnahme bzw. deine Anmeldung auf dieser Website, erteilst du dieser Website deine Einwilligung, deine Daten zu erfassen und zu verarbeiten. Deine Einwilligung kannst du jederzeit widerrufen. Bitte sei aber dar\u00fcber informiert, dass dadurch dein Account gel\u00f6scht und alle weiteren Eintr\u00e4ge und Inhalte von dir auf dieser Webseite entfernt werden.<\/p>\n<p>\t\tDu hast die M\u00f6glichkeit, dich jederzeit mit einer Beschwerde an eine Aufsichtsbeh\u00f6rde wenden, zum Beispiel an die zust\u00e4ndige Aufsichtsbeh\u00f6rde des Bundeslands deines Wohnsitzes oder an die f\u00fcr uns als verantwortliche Stelle zust\u00e4ndige Beh\u00f6rde.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"data\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">03. | Informationen zur Datenverarbeitung<\/h3>\n<p>Deine bei Nutzung dieser Website verarbeiteten Daten werden gel\u00f6scht oder gesperrt, sobald der Zweck der Speicherung entf\u00e4llt, der L\u00f6schung der Daten keine gesetzlichen Aufbewahrungspflichten entgegenstehen und nachfolgend keine anderslautenden Angaben zu einzelnen Verarbeitungsverfahren gemacht werden.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Serverdaten<\/h4>\n<p>Aus technischen Gr\u00fcnden, insbesondere zur Gew\u00e4hrleistung eines sicheren und stabilen Internetauftritts, werden Daten durch deinen Browser an diese Website bzw. an den ISP (Internet Service Provider bzw. Server) \u00fcbermittelt. Mit diesen sogenannten Server-Logfiles werden unter anderem<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Typ und Version deines Browsers,<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">das Betriebssystem,<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">die Website, von der aus du auf die Website von \u00abMen of Wrestling\u00bb gewechselt hast (Referrer-URL),<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Datum und Uhrzeit des jeweiligen Zugriffs sowie die IP-Adresse des Internetanschlusses, von dem aus die Nutzung des Internetauftritts von \u00abMen of Wrestling\u00bb erfolgt, erhoben. Diese so erhobenen Daten werden vorr\u00fcbergehend gespeichert, dies jedoch nicht gemeinsam mit anderen Daten von dir.<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank30\"><\/div>\n<p>Diese Speicherung erfolgt auf der Rechtsgrundlage von Artikel 6 Absatz 1 lit. f.) DSGVO. Diese Website hat ein berechtigtes Interesse an der Verbesserung, Stabilit\u00e4t, Funktionalit\u00e4t und Sicherheit dieses Internetauftritts.<\/p>\n<p>\t\tDie Daten werden sp\u00e4testens nach sieben Tage wieder gel\u00f6scht, soweit keine weitere Aufbewahrung zu Beweiszwecken erforderlich ist. Andernfalls sind die Daten bis zur endg\u00fcltigen Kl\u00e4rung eines Vorfalls ganz oder teilweise von der L\u00f6schung ausgenommen.<\/p>\n<p>\t\tDie Datenbank und die Webseiten dieses Projekts befinden sich auf einem deutschen Server, die von 1&#038;1 Telecom GmbH betrieben werden. Jedoch werden auch die Dienste des Content Delivery Networks (CDN) von Cloudfare Inc. in Anspruch genommen. Bitte lese dir diesbez\u00fcglich den Abschnitt \u00ab<a class=\"aex-imprint-links\" href=\"#cloudfare\" target=\"_self\">Cloudfare<\/a>\u00bb durch.<\/p>\n<p>\t\t1&#038;1 Telecom GmbH<br \/>\n\t\tDatenschutz<br \/>\n\t\tElgendorfer Strasse 57<br \/>\n\t\t56410 Montabaur<br \/>\n\t\tDeutschland<br \/>\n\t\tEurop\u00e4ische Union<\/p>\n<p>\t\tWeitere Information diesbez\u00fcglich findest du in der Datenschutzerkl\u00e4rung von 1&#038;1 Telecom GmbH unter <a class=\"aex-imprint-links\" href=\"https:\/\/1und1.de\/DatenschutzTelecomGmbH\" target=\"_blank\">https:\/\/1und1.de\/DatenschutzTelecomGmbH<\/a>.<\/p>\n<p>\t\tIm Nachfolgenden findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/com\/privacy-policy\/auftragsverarbeitungsvertrag-mit-1und1.pdf\" target=\"_blank\">https:\/\/menofwrestling.com\/com\/privacy-policy\/auftragsverarbeitungsvertrag-mit-1und1.pdf<\/a> den Auftragsverarbeitungsvertrag, der zwischen dieser Website bzw. \u00abAexraex | The Pioneer\u00bb (Aexraex) und 1&#038;1 Telecom GmbH besteht.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">SSL-Verschl\u00fcsselung<\/h4>\n<p>Diese Website nutzt aus Gr\u00fcnden der Sicherheit und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Anfragen, die du an diese Website sendest, eine sichere SSL-Verschl\u00fcsselung.<\/p>\n<p>\t\tEine verschl\u00fcsselte Verbindung erkennst du daran, dass die Adresszeile deines Browsers von \u00abhttp:\/\/\u00bb auf \u00abhttps:\/\/\u00bb wechselt und an dem Schlosssymbol in der Adresszeile deines Browsers. Wenn die SSL Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die du an diese Website \u00fcbermittelst, nicht von Dritten mitgelesen werden.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"ccpa\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">04. | California Consumer Privacy Act<\/h3>\n<p>Beim California Consumer Privacy Act (CCPA) handelt es sich um ein im Juni 2018 verabschiedetes und am 1. Januar 2020 in Kraft getretenes Datenschutzgesetz des U.S.-amerikanischen Bundesstaates Kalifornien, das den Umgang mit personenbezogenen Daten im Verbraucherbereich regelt. Alle Rechte, die dieses Gesetz in Kalifornien seinen B\u00fcrgern einr\u00e4umt, werden in dieser Datenschutzerkl\u00e4rung n\u00e4her erkl\u00e4rt und erl\u00e4utert. Es gew\u00e4hrt allen in Kalifornien lebenden Personen das Recht,<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">zu wissen, ob und welche Daten \u00fcber sie gesammelt werden,<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">zu erfahren, ob ihre Daten verkauft bzw. an andere Personen bzw. Unternehmen weitergegeben werden,<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">die \u00fcber sie gesammelten Informationen jederzeit einzusehen,<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">den Verkauf bzw. die Weitergabe pers\u00f6nlicher Daten zu untersagen und<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">ein Unternehmen zur L\u00f6schung der \u00fcber sie gesammelten Daten aufzufordern.<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank30\"><\/div>\n<p>Die aufgez\u00e4hlten Punkte des California Consumer Privacy Acts sind dabei durch alle Unternehmen, Dienstleister und gewinnorientierten Einrichtungen zu gew\u00e4hrleisten, die personenbezogene Daten sammeln, gesch\u00e4ftlich in Kalifornien t\u00e4tig sind (auch unabh\u00e4ngig von Unternehmenssitz) und dar\u00fcber hinaus einen oder mehrere der folgenden Punkte erf\u00fcllen:<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Der Jahresumsatz (Brutto) betr\u00e4gt 25 Millionen US-Dollar oder mehr,<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Im Jahr werden personenbezogene Daten von 50.000 oder mehr Kunden, Haushalten oder netzwerkf\u00e4higen Ger\u00e4ten in Kalifornien zu kommerziellen Zwecken verwendet (Erhebung, Kauf, Verkauf oder sonstige Weitergabe).<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Mehr als die H\u00e4lfte des Jahresumsatzes stammt aus dem Verkauf personenbezogener Daten von kalifornischen Kunden, Haushalten oder netzwerkf\u00e4higen Ger\u00e4ten.<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank30\"><\/div>\n<p>Diese Website m\u00f6chte betonen, dass zu keiner Zeit pers\u00f6nliche Daten von Nutzern und Betroffenen verschenkt oder verkauft weden.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"cookies\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">5. | Cookies<\/h3>\n<p>Diese Website verwendet f\u00fcr seinen Internetauftritt sogenannte Cookies.<\/p>\n<div class=\"blank50\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Sitzungs-Cookies bzw. sogenannte Session-Cookies<\/h4>\n<p>Cookies sind kleine Textdateien oder andere Speichertechnologien, die durch den von dir eingesetzten Browser auf deinem Endger\u00e4t abgelegt und gespeichert werden. Durch diese Cookies werden im individuellen Umfang bestimmte Informationen von dir, wie beispielsweise deine Browser- oder Standortdaten oder deine IP-Adresse, verarbeitet.<\/p>\n<p>\t\tDurch diese Verarbeitung wird diese Website benutzerfreundlicher, effektiver und sicherer, da die Verarbeitung beispielsweise die Wiedergabe des Internetauftritts in unterschiedlichen Sprachen oder das Angebot einer Warenkorbfunktion erm\u00f6glicht.<\/p>\n<p>\t\tRechtsgrundlage dieser Verarbeitung ist Artikel 6 Absatz 1 lit b.) DSGVO, sofern diese Cookies Daten zur Vertragsanbahnung oder Vertragsabwicklung verarbeitet werden.<\/p>\n<p>\t\tFalls die Verarbeitung nicht der Vertragsanbahnung oder Vertragsabwicklung dient, liegt das berechtigte Interesse dieser Website in der Verbesserung der Funktionalit\u00e4t des Internetauftritts. Rechtsgrundlage ist hierf\u00fcr Artikel 6 Absatz 1 lit. f.) DSGVO.<\/p>\n<p>\t\tMit Schliessen deines Browsers werden diese Session-Cookies gel\u00f6scht.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Cookies von Drittanbietern bzw. externen Anbietern<\/h4>\n<p>Gegebenenfalls werden mit dem Internetauftritt von \u00abMen of Wrestling\u00bb auch Cookies von Partnerunternehmen, mit denen \u00abMen of Wrestling\u00bb zum Zwecke der Gesch\u00e4ftsabwicklung etc., der Analyse oder der Funktionalit\u00e4ten des Internetauftritts zusammenarbeitet, verwendet.<\/p>\n<p>\t\tDie Einzelheiten hierzu, insbesondere zu den Zwecken und den Rechtsgrundlagen der Verarbeitung solcher Drittanbieter-Cookies, entnimmst du bitte den nachfolgenden Informationen.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Das Setzen von Cookies verhindern<\/h4>\n<p>Du kannst das Setzen von Cookies durch eine Einstellung in deinem Browser verhindern oder einschr\u00e4nken. Ebenfalls kannst du bereits gespeicherte Cookies jederzeit l\u00f6schen. Die hierf\u00fcr erforderlichen Schritte und Massnahmen h\u00e4ngen jedoch von deinem konkret genutzten Browser ab.<\/p>\n<p>\t\tBei Fragen hierzu nutzt du bitte am besten die Hilfefunktion oder Dokumentation deines Browsers oder wendest dich an dessen Hersteller bzw. an dessen Support.<\/p>\n<p>\t\tBei sogenannten Flash-Cookies kann die Verarbeitung allerdings nicht \u00fcber die Einstellungen des Browsers unterbunden werden. Stattdessen musst du insoweit die Einstellung deines Flash-Players \u00e4ndern. Auch die hierf\u00fcr erforderlichen Schritte und Massnahmen h\u00e4ngen von deinem konkret genutzten Flash-Player ab. Bei Fragen benutzt du bitte am besten ebenso die Hilfefunktion oder Dokumentation deines Flash-Players oder wendest dich an den Hersteller bzw. an dessen Support.<\/p>\n<p>\t\tSolltest du jedoch das Setzen bzw. die Installation der Cookies verhindern oder einschr\u00e4nken, kann dies allerdings dazu f\u00fchren, dass nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich nutzbar sind!<\/p>\n<p>\t\tJe nach Art der Cookies und deren Zweck werden diese entweder 11 oder 14 Monate gespeichert. Bei deinem ersten Besuch dieser Website hast du die M\u00f6glichkeit, selber dar\u00fcber zu bestimmen, welche Cookies von dir aktiviert oder deaktiviert werden sollen. Einige Cookies k\u00f6nnen nicht deaktiviert werden, weil diese f\u00fcr diese Website und dessen Funktionalit\u00e4t essentiell sind.<\/p>\n<p>\t\tDu kannst einzelne Cookies oder den gesamten Cookie-Bestand l\u00f6schen. Dar\u00fcber hinaus erh\u00e4lst du Informationen und Anleitungen, wie diese Cookies gel\u00f6scht oder deren Speicherung vorab blockiert werden k\u00f6nnen. Je nach Anbieter deines Browsers findest du die notwendigen Informationen unter den nachfolgenden Links:<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">APPLE SAFARI<br \/>\n\t\t\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/support.apple.com\/kb\/PH17191?locale=de_DE&#038;viewlocale=de_DE\" target=\"_blank\">https:\/\/support.apple.com\/kb\/PH17191?locale=de_DE&#038;viewlocale=de_DE<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">GOOGLE CHROME<br \/>\n\t\t\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/support.google.com\/accounts\/answer\/61416?hl=de\" target=\"_blank\">https:\/\/support.google.com\/accounts\/answer\/61416?hl=de<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">MICROSOFT INTERNET EXPLORER BZW. EDGE<br \/>\n\t\t\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/support.microsoft.com\/de-de\/help\/17442\/windows-internet-explorer-delete-manage-cookies\" target=\"_blank\">https:\/\/support.microsoft.com\/de-de\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">MOZILLA FIREFOX<br \/>\n\t\t\t\t<a class=\"aex-imprint-links\" href=\"https:\/\/support.mozilla.org\/de\/kb\/cookies-loeschen-daten-von-websites-entfernen\/\" target=\"_blank\">https:\/\/support.mozilla.org\/de\/kb\/cookies-loeschen-daten-von-websites-entfernen<\/a><\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">OPERA<br \/>\n\t\t\t\t<a class=\"aex-imprint-links\" href=\"http:\/\/www.opera.com\/de\/help\" target=\"_blank\">http:\/\/www.opera.com\/de\/help<\/a><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Cookies individuell einstellen<\/h4>\n<p>In der \u00abCookie Consent Box\u00bb, die du jederzeit unten rechts auf der Website aufrufen kannst, hast du als Nutzer dieser Website die M\u00f6glichkeit, Cookies zu aktvieren bzw. zu deaktivieren. Diese Box l\u00e4sst sich minimieren und du kannst jederzeit auf jeder Unterseite auf diese Box zugreifen. Es gibt jedoch einige Cookies, die f\u00fcr den Betrieb dieser Website essentiell und unbedingt erforderlich sind. Diese kann man nicht deaktivieren.<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n\t\t\t<style>.cmplz-status-accepted,.cmplz-status-denied {display: none;}<\/style>\n\t\t\t\t<script>\n\t\t\t\tdocument.addEventListener('cmplz_before_cookiebanner', function(){\n                    if (cmplz_has_consent('marketing')) {\n\t\t\t\t        document.querySelector('.cmplz-status-accepted').style.display = 'block';\n\t\t\t\t        document.querySelector('.cmplz-status-denied').style.display = 'none';\n\t\t\t\t    } else {\n\t\t\t\t\t\tdocument.querySelector('.cmplz-status-accepted').style.display = 'none';\n\t\t\t\t        document.querySelector('.cmplz-status-denied').style.display = 'block';\n\t\t\t\t\t\tdocument.querySelector('.cmplz-revoke-custom').setAttribute('disabled', true);\n\n\t\t\t\t    }\n                    document.addEventListener('click', e => {\n\t\t\t\t\t\tif ( e.target.closest('.cmplz-revoke-custom') ) {\n\t\t\t\t\t\t\tdocument.querySelector('.cmplz-revoke-custom').setAttribute('disabled', true);\n                            cmplz_set_banner_status('dismissed');\n\t\t\t\t\t\t}\n\t\t\t\t\t});\n                    document.addEventListener('click', e => {\n\t\t\t\t\t\tif ( e.target.closest('.cmplz-accept') ) {\n                            document.querySelector('.cmplz-status-accepted').style.display = 'block';\n\t\t\t\t        \tdocument.querySelector('.cmplz-status-denied').style.display = 'none';\n\t\t\t\t\t\t\tdocument.querySelector('.cmplz-revoke-custom').removeAttribute('disabled');\n\t\t\t\t\t\t}\n\t\t\t\t\t});\n\t\t\t\t});\n\t\t\t<\/script><button class=\"cmplz-deny cmplz-revoke-custom\">Widerrufe deine Einstellungen<\/button>&nbsp;<span class=\"cmplz-status-accepted\">Current status: Accepted<\/span><span class=\"cmplz-status-denied\">Current status: Denied<\/span>\n\t\t\t<br \/>\n\t\t\t<div id=\"cmplz-manage-consent-container-nojavascript\">You have loaded the Cookie Policy without javascript support.&nbsp;On AMP, you can use the manage consent button on the bottom of the page.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div>\n\t\t\t<br \/>\n\t\t\t<div id=\"cmplz-cookies-overview\"><\/div>\n\t\t<\/div>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Affilinet-Tracking-Cookies<\/h4>\n<p>Gegenw\u00e4rtig werden keine Dienste vom Affilinet-Netzwerk auf dieser Website genutzt bzw. Cookies von diesem eingesetzt. Falls jedoch zu gegebener Zeit dieser Dienst in Anspruch genommen werden sollte, gilt das Folgende:<\/p>\n<p>\t\tAuf dieser Website werden Angebote und Leistungen Dritter beworben. Sofern du aufgrund von Werbung, befindlich auf diesen Seiten, f\u00fcr diese Drittangebote einen Vertrag mit dem Drittanbieter schliesst, erh\u00e4lt der Betreiber dieser Website hierf\u00fcr eine Provision.<\/p>\n<p>\t\tUm die erfolgreiche Vermittlung korrekt erfassen zu k\u00f6nnen, setzt diese Website das sogenannte Affilinet-Tracking-Cookie ein. Dieses Cookie speichert aber keine deiner personenbezogenen Daten. Es wird lediglich die Identifikationsnummer von dieser Website als vermittelnder Anbieter sowie die Ordnungsnummer des von dir angeklickten Werbemittels (beispielsweise eines Banners oder eines Textlinks) erfasst. Diese Informationen werden von dieser Website zum Zwecke der Zahlungsabwicklung bzw. Auszahlung seiner Provisionen ben\u00f6tigt.<\/p>\n<p>\t\tFalls du mit dieser Verarbeitung nicht einverstanden bist, hast du die M\u00f6glichkeit, die Speicherung der Cookies durch eine Einstellung in deinem Browser zu verhindern oder diese Cookies im Cookie-Fenster bei deinem ersten Besuch dieser Website zu deaktivieren.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Facebook Pixel<\/h4>\n<p>Der Betreiber dieser Website m\u00f6chte besonders hervorheben, dass der Webanalysedienst von Facebook, mit dem Namen Facebook Pixel, auf diesen Webseiten nicht eingesetzt wird, damit deine Besuche dieser Website nicht direkt oder indirekt getrackt werden k\u00f6nnen.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"vertrag\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">6. | Vertragsabwicklung<\/h3>\n<p>Gegenw\u00e4rtig werden keine kommerziellen Features und Leistungen angeboten. Falls aber zu gegebener Zeit zahlungspflichtige Angebote hinzukommen sollten, gilt diesbez\u00fcglich das Folgende:<\/p>\n<p>\t\tDie von dir zur Inanspruchnahme des Waren- und\/oder Dienstleistungsangebots \u00fcbermittelten Daten werden von dieser Website zum Zwecke der Vertragsabwicklung verarbeitet und sind insoweit erforderlich. Vertragsschluss und Vertragsabwicklung sind ohne Bereitstellung deiner Daten nicht m\u00f6glich.<\/p>\n<p>\t\tRechtsgrundlage f\u00fcr die Verarbeitung ist Artikel 6 Absatz 1 lit. b.) DSGVO.<\/p>\n<p>\t\tDiese Website l\u00f6scht Daten mit vollst\u00e4ndiger und abgeschlossener Vertragsabwicklung, muss aber dabei jeoch die steuer- und handelsrechtlichen Aufbewahrungsfristen beachten.<\/p>\n<p>\t\tIm Rahmen der Vertragsabwicklung gibt diese Website deine Daten an das mit der Warenlieferung bzw. Bezahlung beauftragte Unternehmen oder an den Finanzdienstleister weiter, soweit die Weitergabe zur Warenauslieferung oder zu Bezahlzwecken erforderlich ist.<\/p>\n<p>\t\tRechtsgrundlage f\u00fcr die Weitergabe der Daten ist hierf\u00fcr Artikel 6 Absatz 1 lit. b.) DSGVO.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Externe Zahlungsanbieter<\/h4>\n<p>Diese Website setzt externe Zahlungsdienstleister ein, \u00fcber deren Plattformen die Nutzer und diese Website Zahlungstransaktionen vornehmen k\u00f6nnen. Folgende Dienste von den nachfolgenden Finanzdienstleistern k\u00f6nnen f\u00fcr Transaktionen in Anspruch genommen werden:<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">American Express<br \/>\n\t\t\t\tDatenschutzinformationen bez\u00fcglich American Express findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/americanexpress.com\/de\/content\/privacy-policy-statement.html\" target=\"_blank\">https:\/\/americanexpress.com\/de\/content\/privacy-policy-statement.html<\/a>.<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Giropay<br \/>\n\t\t\t\tDatenschutzinformationen bez\u00fcglich Giropay findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/giropay.de\/rechtliches\/datenschutz-agb\/\" target=\"_blank\">https:\/\/giropay.de\/rechtliches\/datenschutz-agb\/<\/a>.<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Klarna<br \/>\n\t\t\t\tDatenschutzinformationen bez\u00fcglich Klarna findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/klarna.com\/de\/datenschutz\/\" target=\"_blank\">https:\/\/klarna.com\/de\/datenschutz\/<\/a>.<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Mastercard<br \/>\n\t\t\t\tDatenschutzinformationen bez\u00fcglich Mastercard findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/mastercard.de\/de-de\/datenschutz.html\" target=\"_blank\">https:\/\/mastercard.de\/de-de\/datenschutz.html<\/a>.<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">PayPal<br \/>\n\t\t\t\tDatenschutzinformationen bez\u00fcglich PayPal findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/paypal.com\/de\/webapps\/mpp\/ua\/privacy-full\/\" target=\"_blank\">https:\/\/paypal.com\/de\/webapps\/mpp\/ua\/privacy-full\/<\/a>.<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Skrill<br \/>\n\t\t\t\tDatenschutzinformationen bez\u00fcglich Skrill findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/skrill.com\/de\/fusszeile\/datenschutzrichtlinie\/\" target=\"_blank\">https:\/\/skrill.com\/de\/fusszeile\/datenschutzrichtlinie\/<\/a>.<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">Visa<br \/>\n\t\t\t\tDatenschutzinformationen bez\u00fcglich Visa findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/visa.de\/datenschutz\/\" target=\"_blank\">https:\/\/visa.de\/datenschutz\/<\/a>.<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank50\"><\/div>\n<p>Im Rahmen der Erf\u00fcllung von Vertr\u00e4gen setzt diese Website die Zahlungsdienstleister auf Grundlage des Artikel 6 Absatz 1 lit. b.) DSGVO ein. Im \u00dcbrigen setzt diese Website externe Zahlungsdienstleister auf Grundlage von berechtigten Interessen gem\u00e4ss Artikel 6 Absatz 1 lit. f.) DSGVO ein, um seinen Nutzern effektive und sichere Zahlungsm\u00f6glichkeit zu bieten.<\/p>\n<p>\t\tZu den, durch die Zahlungsdienstleister verarbeiteten Daten geh\u00f6ren Daten, wie beispielsweise der Name und die Adresse, Bankdaten (Kontonummern oder Kreditkartennummern), Passw\u00f6rter, TANs und Pr\u00fcfsummen sowie die Vertrags-, Summen und empf\u00e4ngerbezogenen Angaben. Die Angaben sind erforderlich, um die Transaktionen durchzuf\u00fchren. Die eingegebenen Daten werden jedoch nur durch die Zahlungsdienstleister verarbeitet und bei diesen gespeichert. Diese Website erh\u00e4lt keine konto- oder kreditkartenbezogenen Informationen, sondern nur Informationen mit Best\u00e4tigung oder Negativbeauskunftung der Zahlung. Unter Umst\u00e4nden werden die Daten seitens der Zahlungsdienstleister an Wirtschaftsauskunfteien \u00fcbermittelt. Diese \u00dcbermittlung bezweckt die Identit\u00e4ts- und Bonit\u00e4tspr\u00fcfung. Hierzu verweist diese Website auf die Allgemeinen Gesch\u00e4ftsbedingungen und Datenschutzhinweise der Zahlungsdienstleister.<\/p>\n<p>\t\tF\u00fcr die Zahlungsgesch\u00e4fte gelten die Gesch\u00e4ftsbedingungen und die Datenschutzhinweise der jeweiligen Zahlungsdienstleister, welche innerhalb der jeweiligen Webseiten bzw. Transaktionsapplikationen abrufbar sind. Diese Website verweist auf diese ebenfalls zwecks weiterer Informationen und Geltendmachung von Widerrufs-, Auskunfts- und anderen Betroffenenrechten.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"account\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">07. | Registrierung, Account und K\u00fcndigung<\/h3>\n<p>Wenn du dich als Nutzer f\u00fcr dieses Projekt registrierst, wird nach erfolgreicher Anmeldung f\u00fcr dich ein Account (Kundenkonto) angelegt.<\/p>\n<p>\t\tDiese Website wird die von dir bei der Registrierung eingegebenen Daten (beispielsweise deinen Usernamen, deine E-Mail-Adresse etc.) ausschliesslich f\u00fcr (vor-)vertragliche Leistungen, f\u00fcr die Vertragserf\u00fcllung und\/oder zum Zwecke der Kundenpflege (beispielsweise um dir eine \u00dcbersicht \u00fcber deine bisherigen Bestellungen\/Downloads zur Verf\u00fcgung zu stellen oder um dir die sogenannte Merkzettelfunktion anbieten zu k\u00f6nnen) erheben und speichern. Gleichzeitig speichert diese Website dabei die IP-Adresse und das Datum deiner Registrierung\/Kauf nebst Uhrzeit.<\/p>\n<p>\t\tIm Rahmen des weiteren Anmeldevorgangs wird deine Einwilligung in diese Verarbeitung eingeholt und auf diese Datenschutzerkl\u00e4rung, die Nutzungsbedingungen und die Allgemeinen Gesch\u00e4ftsbedingungen dieser Website verwiesen. Die dabei von dieser Website erhobenen Daten werden f\u00fcr die Zurverf\u00fcgungstellung des Kundenkontos verwendet.<\/p>\n<p>\t\tSoweit du in diese Verarbeitung einwilligst, ist Artikel 6 Absatz 1 lit. a.) DSGVO Rechtsgrundlage f\u00fcr die Verarbeitung.<\/p>\n<p>\t\tSofern die Er\u00f6ffnung des Kundenkontos zus\u00e4tzlich auch vorvertraglichen Massnahmen oder der Vertragserf\u00fcllung dient, so ist Rechtsgrundlage f\u00fcr diese Verarbeitung auch noch Artikel 6 Absatz 1 lit. b.) DSGVO.<\/p>\n<p>\t\tDie an diese Website erteilte Einwilligung in die Er\u00f6ffnung und den Unterhalt des Kundenkontos kannst du gem\u00e4ss Artikel 7 Absatz 3 DSGVO jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Hierzu musst du dieser Website lediglich \u00fcber deinen Widerruf in Kenntnis setzen. Sei aber bitte dar\u00fcber informiert, dass dadurch dein Konto und weitere Inhalte von dir gel\u00f6scht werden.<\/p>\n<p>\t\tDie insoweit erhobenen Daten werden gel\u00f6scht, sobald die Verarbeitung nicht mehr erforderlich ist. Hierbei muss aber diese Website steuer- und handelsrechtliche Aufbewahrungsfristen beachten.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">K\u00fcndigung und L\u00f6schen des Accounts<\/h4>\n<p>Der Nutzer darf seine Mitgliedschaft bzw. sein Account jederzeit ohne Angabe von Gr\u00fcnden k\u00fcndigen. Ebenfalls darf diese Website einen Nutzer jederzeit ohne Angabe von Gr\u00fcnden entweder blockieren, ausschliessen oder dauerhaft l\u00f6schen. Bei L\u00f6schung des Accounts bedarf es keiner Einhaltung einer K\u00fcndigungsfrist.<\/p>\n<p>\t\tInsbesondere wird das Konto eines Nutzers dauerhaft gel\u00f6scht, wenn es gegen die Nutzungsbedingungen der Community verst\u00f6sst.<\/p>\n<p>\t\tDer Nutzer, der gegen die Nutzungsbedingungen der Community verst\u00f6sst, muss nicht zwangsl\u00e4ufig vorher von dieser Website gewarnt oder informiert werden.<\/p>\n<p>\t\tDiese Website r\u00e4umt sich das Recht ein, die Registrierung von Nutzern ohne Angabe von Gr\u00fcnden abzulehnen. Dies wird insbesondere dann erfolgen, wenn der Betreiber dieser Website sicherheitsrelevante Gr\u00fcnde f\u00fcr eine Ablehnung hat.<\/p>\n<p>\t\tNachdem das Konto gel\u00f6scht wurde, werden Daten des Nutzers aus der Datenbank entfernt. Bis die Daten vollst\u00e4ndig aus den Datenbanken entfernt worden sind, kann dies bis zu 14 Tage dauern.<\/p>\n<p>\t\tFalls bei einer vorliegenden rechtswidrigen Handlung die Daten, trotz L\u00f6schung des Accounts, seitens einer rechtlichen Beh\u00f6rde zu Nachweiszwecken ben\u00f6tigt werden sollten, werden die Daten erst nach Abschluss des einzelnen Falles zeitnah gel\u00f6scht.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"newsletter\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">08. | Newsletter<\/h3>\n<p>Falls du dich f\u00fcr den Erhalt des kostenlosen Newsletters anmeldest, werden die von dir hierzu abgefragten Daten, also deine E-Mail-Adresse sowie dein Name und deine Anschrift (optional), an diese Website \u00fcbermittelt.<\/p>\n<p>\t\tGleichzeitig speichert diese Website die IP-Adresse des Internetanschlusses von dem aus du auf dieses Projekt zugreifst, sowie Datum und Uhrzeit deiner Anmeldung.<\/p>\n<p>\t\tIm Rahmen des weiteren Anmeldevorgangs wird diese Website deine Einwilligung in die \u00dcbersendung des Newsletters einholen, den Inhalt des Newsletters beschreiben und auf diese Datenschutzerkl\u00e4rung verweisen. Die dabei erhobenen Daten verwendet diese Website ausschliesslich f\u00fcr den Versand von Newslettern. Diese Daten weden insbesondere auch nicht an Dritte weitergegeben.<\/p>\n<p>\t\tRechtsgrundlage hierbei ist Artikel 6 Absatz 1 lit. a.) DSGVO.<\/p>\n<p>\t\tDie Einwilligung f\u00fcr den Erhalt von Newslettern kannst du gem\u00e4ss Artikel 7 Absatz 3 DSGVO jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Hierzu musst du den Betreiber dieser Website lediglich \u00fcber deinen Widerruf in Kenntnis setzen oder den in jedem Newsletter enthaltenen Abmeldelink bet\u00e4tigen.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Newsletter per MailChimp<\/h4>\n<p>Gegenw\u00e4rtig werden keine Newsletter per MailChimp versandt. Falls jedoch zu gegebener Zeit dieser Dienst in Anspruch genommen werden sollte, gilt das Folgende:<\/p>\n<p>\t\tZum Newsletterversand nutzt diese Website den Dienst von MailChimp (nachfolgende \u00abThe Rocket Science Group\u00bb genannt).<\/p>\n<p>\t\tThe Rocket Science Group, LLC<br \/>\n\t\t512 Means Street<br \/>\n\t\tSuite 404<br \/>\n\t\tAtlanta<br \/>\n\t\tGA 30318<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDiese Website m\u00f6chte dich dar\u00fcber informieren, dass durch diesen Dienst unter Umst\u00e4nden deine Daten in die U.S.A. gesendet und dort verarbeitet werden k\u00f6nnen. The Rocket Science Group unter <a class=\"aex-imprint-links\" href=\"http:\/\/mailchimp.com\/legal\/privacy\/\" target=\"_blank\">http:\/\/mailchimp.com\/legal\/privacy\/<\/a> bietet hier\u00fcber weitergehende Datenschutzinformationen an.<\/p>\n<p>\t\tFalls du dich f\u00fcr den Empfang des Newsletters anmeldest, werden die w\u00e4hrend des Anmeldevorgangs abgefragten Daten, wie deine E-Mail-Adresse sowie (optional) dein Name neben deiner Anschrift, durch The Rocket Science Group verarbeitet. Zudem wird deine IP-Adresse sowie das Datum deiner Anmeldung neben der Uhrzeit gespeichert. Im Rahmen des weiteren Anmeldevorgangs wird deine Einwilligung in die \u00dcbersendung des Newsletters eingeholt, der Inhalt konkret beschrieben und auf diese Datenschutzerkl\u00e4rung verwiesen.<\/p>\n<p>\t\tDer anschliessend \u00fcber The Rocket Science Group versandte Newsletter enth\u00e4lt zudem einen sogenannten Z\u00e4hlpixel, auch Web Beacon genannt. Mit Hilfe dieses Z\u00e4hlpixels kann diese Website auswerten, ob und wann du den Newsletter gelesen hast und ob du die in dem Newsletter etwaig enthaltenen weiterf\u00fchrenden Links gefolgt bist. Neben weiteren technischen Daten, wie zum Beispiel die Daten deines Betriebssystems und deine IP-Adresse, werden die dabei verarbeiteten Daten gespeichert, damit diese Website Newsletter optimieren und auf die W\u00fcnsche der Nutzer eingehen kann. Die Daten werden also zur Steigerung der Qualit\u00e4t und Attraktivit\u00e4t des Newsletters verwendet.<\/p>\n<p>\t\tRechtsgrundlage f\u00fcr den Versand des Newsletters und die Analyse ist Artikel 6 Absatz 1 lit. a.) DSGVO.<\/p>\n<p>\t\tDie Einwilligung f\u00fcr den Erhalt des Newsletters kannst du gem\u00e4ss Artikel 7 Absatz 3 DSGVO jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Hierzu musst du den Betreiber dieser Website lediglich \u00fcber deine Widerruf in Kenntnis setzen oder den in jedem Newsletter enthaltenen Abmeldelink bet\u00e4tigen.<\/p>\n<p>\t\tMit deinem Besuch dieser Website und der Nutzung dieses Angebots erkl\u00e4rst du dich damit f\u00fcr einverstanden.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Newsletter per WhatsApp<\/h4>\n<p>Gegenw\u00e4rtig werden keine Newsletter per WhatsApp versandt. Falls jedoch zu gegebener Zeit dieser Dienst in Anspruch genommen werden sollte, gilt das Folgende:<\/p>\n<p>\t\tDen kostenlosen Newsletter dieser Website kannst du auch \u00fcber den Instant Messaging-Dienst WhatsApp beziehen. WhatsApp ist ein Dienst der WhatsApp Ireland Limited (nachfolgend \u00abWhatsApp\u00bb genannt).<\/p>\n<p>\t\tWhatsApp Ireland Limited<br \/>\n\t\t4 Grand Canal Square<br \/>\n\t\tGrand Canal Harbour<br \/>\n\t\tDublin 2<\/p>\n<p>\t\tWhatsApp Ireland Limited ist ein Tochterunternehmen der WhatsApp Inc. (nachfolgend \u00abWhatsApp\u00bb genannt).<\/p>\n<p>\t\tWhatsApp Inc.<br \/>\n\t\t1601 Willow Road<br \/>\n\t\tMenlo Park<br \/>\n\t\tCalifornia 94025<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDiese Website m\u00f6chte dich dar\u00fcber informieren, dass durch diesen Dienst unter Umst\u00e4nden deine Daten in die U.S.A. gesendet und dort verarbeitet werden k\u00f6nnen. Teilweise erfolgt die Verarbeitung der Nutzerdaten auf Servern von WhatsApp in den U.S.A.. WhatsApp bietet unter <a class=\"aex-imprint-links\" href=\"https:\/\/whatsapp.com\/legal\/#privacy-policy\/\" target=\"_blank\">https:\/\/whatsapp.com\/legal\/#privacy-policy\/<\/a> weitergehende Datenschutzinformationen an.<\/p>\n<p>\t\tUm den Newsletter per WhatsApp empfangen zu k\u00f6nnen, ben\u00f6tigst du ein WhatsApp-Nutzerkonto. Einzelheiten dar\u00fcber, welche Daten WhatsApp bei der Registrierung erhebt, kannst du den vorgenannten Datenschutzinformationen von WhatsApp entnehmen.<\/p>\n<p>\t\tFalls du dich f\u00fcr den Erhalt des Newsletters per WhatApp anmeldest, wird die von dir w\u00e4hrend des Anmeldevorgangs eingegebene Mobilfunknummer durch WhatsApp verarbeitet. Zudem werden deine IP-Adresse sowie das Datum deiner Anmeldung und Uhrzeit gespeichert. Im Rahmen des weiteren Anmeldevorgangs wird deine Einwilligung in die \u00dcbersendung des Newsletters eingeholt, der Inhalt beschrieben und auf diese Datenschutzerkl\u00e4rung verwiesen.<\/p>\n<p>\t\tRechtsgrundlage f\u00fcr den Versand des Newsletters und die Analyse ist Artikel 6 Absatz 1 lit. a.) DSGVO.<\/p>\n<p>\t\tDie Einwilligung f\u00fcr den Erhalt des Newsletters kannst du gem\u00e4ss Artikel 7 Absatz 3 DSGVO jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Hierzu musst du den Betreiber dieser Website lediglich \u00fcber deinen Widerruf in Kenntnis setzen. Ebenfalls kannst du den Newsletterempfang durch eine Einstellung in der WhatsApp-App auf deinem Endger\u00e4t blockieren.<\/p>\n<p>\t\tMit deinem Besuch dieser Website und der Nutzung dieses Angebots erkl\u00e4rst du dich damit f\u00fcr einverstanden.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"contact\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">09. | Kontakt<\/h3>\n<p>Sofern du per Kontaktformular oder E-Mail mit dieser Website in Kontakt trittst, werden die dabei von dir angegebenen Daten zur Bearbeitung deiner Anfrage genutzt.<\/p>\n<p>\t\tDie Angabe der Daten ist zur Bearbeitung und Beantwortung deiner Anfrage erforderlich. Ohne Bereitstellung dieser Daten kann deine Anfrage bzw. dein Anliegen nicht oder allenfalls nur eingeschr\u00e4nkt beantwortet werden.<\/p>\n<p>\t\tRechtsgrundlage f\u00fcr diese Verarbeitung ist Artikel 6 Absatz 1 lit. b.) DSGVO.<\/p>\n<p>\t\tDeine Daten werden gel\u00f6scht, sofern deine Anfrage abschliessend beantwortet worden ist und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen, wie beispielsweise bei einer anschliessenden Vertragsabwicklung.<\/p>\n<p>\t\tUnter \u00ab<a class=\"aex-imprint-links\" href=\"https:\/\/menofwrestling.com\/de\/contact\/\" target=\"_self\">Kontakt<\/a>\u00bb kannst du gerne mit dieser Website in Kontakt treten.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"comments\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">10. | Nutzerbeitr\u00e4ge, Kommentare und Bewertungen<\/h3>\n<p>Diese Website bietet auf seinen Seiten an, Fragen, Antworten, Meinungen, Kommentare oder Bewertungen etc. (nachfolgend nur \u00abBeitr\u00e4ge\u00bb genannt), zu ver\u00f6ffentlichen.<\/p>\n<p>\t\tSofern du dieses Angebot in Anspruch nimmst, verarbeitet und ver\u00f6ffentlicht diese Website deinen Beitrag, Datum und Uhrzeit der Einreichung sowie das von dir gegebenenfalls genutzte Pseudonym bzw. den Usernamen. Falls Du mit deinem Realnamen agieren solltest, kann dieser Beitrag ebenfalls auf diesen Seiten ver\u00f6ffentlicht werden.<\/p>\n<p>\t\tRechtsgrundlage hierbei ist Artikel 6 Absatz 1 lit. a.) DSGVO. Die Einwilligung kannst du gem\u00e4ss Artikel 7 Absatz 3 DSGVO jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Hierzu musst du den Betreiber dieser Website lediglich \u00fcber deinen Widerruf in Kenntnis setzen. Jedoch besteht auch die M\u00f6glichkeit, den eigenen Beitrag selbst \u00fcber die L\u00f6schfunktion zu entfernen.<\/p>\n<p>\t\tFalls zu dem jeweiligen Account des Nutzers ein Profilphoto bzw. Gravatar (Avatar) anh\u00e4ngig sein sollte, also vom Nutzer ein Bild seiner eigenen Person hochgeladen worden sein sollte, wird dieses Bild neben diesem Beitrag ebenfalls ver\u00f6ffentlicht.<\/p>\n<p>\t\tDar\u00fcber hinaus verarbeitet diese Website auch deine IP- und E-Mail-Adresse. Die IP-Adresse wird verarbeitet, weil diese Website ein berechtigtes Interesse daran hat, weitere Schritte einzuleiten oder zu unterst\u00fctzen, sofern der Beitrag in Rechte Dritter eingreift und\/oder dieser Beitrag sonst wie rechtswidrig erfolgt.<\/p>\n<p>\t\tRechtsgrundlage ist in diesem Fall Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse dieser Website liegt in der gegebenenfalls notwendigen Rechtsverteidigung.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"abonnement\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">11. | Abonnieren von Beitr\u00e4gen<\/h3>\n<p>Sofern Beitr\u00e4ge auf dieser Website ver\u00f6ffentlicht werden, bietet dir diese Website zus\u00e4tzlich an, etwaige Folgebeitr\u00e4ge Dritter zu abonnieren.<\/p>\n<p>\t\tUm dich \u00fcber diese Folgebeitr\u00e4ge per E-Mail informieren zu k\u00f6nnen, verarbeitet diese Website hierf\u00fcr deine E-Mail-Adresse und deinen Namen. Rechtsgrundlage hierbei ist Artikel 6 Absatz 1 lit. a.) DSGVO. Die Einwilligung in dieses Abonnement kannst du gem\u00e4ss Artikel 7 Absatz 3 DSGVO jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Hierzu musst du den Betreiber lediglich \u00fcber deinen Widerruf in Kenntnis setzen oder den in der jeweiligen E-Mail enthaltenen Abmeldelink bet\u00e4tigen.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"google-adsense\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">12. | Google Ads<\/h3>\n<p>Auf dieser Website werden Werbeanzeigen von Google AdSense eingesetzt. Es handelt sich hierbei um einen Dienst der Google LLC (nachfolgend \u00abGoogle\u00bb genannt).<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDurch Google AdSense werden Cookies sowie sogenannte \u00abWeb Beacons\u00bb \u00fcber deinen Browser auf deinem Endger\u00e4t gespeichert. Hierdurch erm\u00f6glicht Google dieser Website die Analyse der Nutzung dieses Internetauftritts durch dich. Die so erfassten Informationen werden neben deiner IP-Adresse und der dir angezeigten Werbeformate an Google in die U.S.A. \u00fcbertragen und dort gespeichert. Ferner kann Google diese Informationen an Vertragspartner weitergeben. Google erkl\u00e4rt allerdings, dass deine IP-Adresse nicht mit anderen Daten von dir zusammengef\u00fchrt werden.<\/p>\n<p>\t\tRechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse von dieser Website liegt in der Analyse, Optimierung und dem wirtschaftlichen Betrieb dieses Internetauftritts.<\/p>\n<p>\t\tSofern du mit dieser Verarbeitung nicht einverstanden bist, hast du die M\u00f6glichkeit, beispielsweise die Installation der Cookies durch die entsprechenden Einstellungen in deinem Browser zu verhindern. Einzelheiten hierzu findest du vorstehend unter dem Punkt \u00abCookies\u00bb.<\/p>\n<p>\t\tZudem bietet Google unter <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a> und <a class=\"aex-imprint-links\" href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\">https:\/\/adssettings.google.com\/authenticated<\/a> weitere Informationen an und zwar insbesondere zu den M\u00f6glichkeiten der Unterbindung der Datennutzung.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"google-ads\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">13. | Google Ads mit Conversion-Tracking (Google AdWords)<\/h3>\n<p>Diese Website setzt Werbekomponenten von Google AdWords und dabei das sogenannte Conversion-Tracking ein. Es handelt sich hierbei um einen Dienst der Google LLC (nachfolgend \u00abGoogle\u00bb genannt).<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDiese Website nutzt das Conversion-Tracking zur zielgerichteten Bewerbung dieses Angebots. Rechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse liegt in der Analyse, Optimierung und dem wirtschaftlichen Betrieb dieses Internetauftritts.<\/p>\n<p>\t\tFalls du auf eine von Google geschaltete Anzeige klickst, speichert das von dieser Website eingesetzte Conversion-Tracking ein Cookie auf deinem Endger\u00e4t. Diese sogenannten Conversion-Cookies verlieren mit Ablauf von 30 Tagen ihre G\u00fcltigkeit und dienen im \u00dcbrigen nicht deiner pers\u00f6nlichen Identifikation.<\/p>\n<p>\t\tSofern das Cookie noch g\u00fcltig ist und du eine bestimmte Seite dieses Internetauftritts besuchst, kann sowohl diese Website als auch Google auswerten, dass du auf den von dieser Website bei Google platzierten Anzeigen geklickt hast und dass du anschliessend auf diesen Internetauftritt weitergeleitet worden bist.<\/p>\n<p>\t\tDiese Daten werden an Server von Google in die U.S.A. gesendet und dort verarbeitet.<\/p>\n<p>\t\tDurch die so eingeholten Informationen erstellt Google dieser Website eine Statistik \u00fcber deinen Besuch dieses Internetauftritts. Zudem erh\u00e4lt diese Website hierdurch Informationen \u00fcber die Anzahl der Nutzer, die auf die Anzeigen dieser Website geklickt haben sowie \u00fcber die anschliessend aufgerufenen Seiten dieses Internetauftritts. Weder diese Website noch Dritte, die ebenfalls Google AdWords einsetzten, werden hierdurch allerdings in die Lage versetzt, dich auf diesem Wege zu identifizieren.<\/p>\n<p>\t\tDurch die entsprechenden Einstellungen deines Browsers kannst du zudem die Installation der Cookies verhindern oder einschr\u00e4nken. Gleichzeitig kannst du bereits gespeicherte Cookies jederzeit l\u00f6schen. Die hierf\u00fcr erforderlichen Schritte und Massnahmen h\u00e4ngen jedoch von deinem genutzten Browser ab. Bei Fragen hierzu benutze bitte die Hilfefunktion oder die Dokumentation deines Browsers oder wende dich an dessen Hersteller bzw. an dessen Support.<\/p>\n<p>\t\tN\u00e4here Informationen \u00fcber die Datenverarbeitung durch Google kannst du den Google-Datenschutzhinweisen entnehmen: <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a>. Dort kannst du im Datenschutzcenter auch deine pers\u00f6nlichen Datenschutz-Einstellungen ver\u00e4ndern.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"google-analytics\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">14. | Google Analytics<\/h3>\n<p>Soweit du deine Einwilligung gegeben hast, wird auf dieser Website Google Analytics eingesetzt. Um diese Website und dessen Funktionalit\u00e4t analysieren zu k\u00f6nnen, nutzt diese Website die Dienste dieses externen Anbieters. Diese Analyse wird seitens Google zur Verf\u00fcgung gestellt und heisst Google Analytics (nachfolgend nur \u00abGoogle\u00bb genannt).<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDer Dienst Google Analytics dient zur Analyse des Nutzungsverhaltens dieses Internetauftritts. Rechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse dieser Website liegt in der Analyse, Optimierung und dem wirtschaftlichen Betrieb dieses Internetauftritts.<\/p>\n<p>\t\tNutzungs- und nutzerbezogene Informationen, wie beispielsweise IP-Adresse, Ort, Zeit oder H\u00e4ufigkeit des Besuchs des Internetauftritts, werden dabei an einen Server von Google in den U.S.A. \u00fcbertragen und dort gespeichert. Allerdings nutzt diese Website Google Analytics mit der sogenannten Anonymisierungsfunktion. Durch diese Funktion k\u00fcrzt Google die IP-Adresse schon innerhalb der E.U. bzw. des Europ\u00e4ischen Wirtschaftsraums. Diese Website kann jedoch nicht garantieren, dass deine IP-Adresse in den U.S.A. gek\u00fcrzt wird.<\/p>\n<p>\t\tDie so erhobenen Daten werden wiederum von Google genutzt, um dieser Website eine Auswertung \u00fcber den Besuch des Internetauftritts sowie \u00fcber die dortigen Nutzungsaktivit\u00e4ten zur Verf\u00fcgung zu stellen. Auch k\u00f6nnen diese Daten genutzt werden, um weitere Dienstleistungen zu erbringen, die mit der Nutzung dieses Internetauftritts und der Nutzung des Internets zusammenh\u00e4ngen.<\/p>\n<p>\t\tGoogle gibt an, deine IP-Adresse nicht mit anderen Daten zu verbinden. Zudem h\u00e4lt Google unter <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/technologies\/partner-sites?hl=de\" target=\"_blank\">https:\/\/policies.google.com\/technologies\/partner-sites?hl=de<\/a> weitere datenschutzrechtliche Informationen f\u00fcr dich bereit, so beispielsweise auch zu den M\u00f6glichkeiten, die Datennutzung zu unterbinden. Weitere Informationen zu Nutzungsbedingungen und Datenschutz findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/www.google.com\/analytics\/terms\/de.html\" target=\"_blank\">https:\/\/www.google.com\/analytics\/terms\/de.html<\/a> und unter <a class=\"aex-imprint-links\" href=\"https:\/\/www.google.com\/analytics\/terms\/de.html\" target=\"_blank\">https:\/\/policies.google.com\/?hl=de<\/a>.<\/p>\n<p>\t\tZudem bietet Google unter <a class=\"aex-imprint-links\" href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a> ein sogenanntes Deaktivierungs-Add-On neben weiteren Informationen hierzu an. Dieses Add-On l\u00e4sst sich mit den g\u00e4ngigen Browsern installieren und bietet dir weitergehende Kontrollm\u00f6glichkeit \u00fcber die Daten, die Google bei Aufruf dieses Internetauftritts durch dich erfasst. Dabei teilt das Add-On dem JavaScript (ga.js) von Google Analytics mit, dass Informationen zum Besuch dieses Internetauftritts nicht an Google Analytics \u00fcbermittelt werden sollen. Dies verhindert aber nicht, dass Informationen an diese Website oder an andere Webanalysedienste \u00fcbermittelt werden.<\/p>\n<p>\t\tDiese Daten werden seitens Google f\u00fcr 14 Monate gespeichert. Nach Ablauf dieser Zeit werden diese Daten seitens Google gel\u00f6scht.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">IP-Anonymisierung von Google Analytics<\/h4>\n<p>Diese Website nutzt, wie oben bereits erw\u00e4hnt, die sogenannten Anonymisierungsfunktion von Google Analytics. Dadurch wird deine IP-Adresse von Google innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt.<\/p>\n<p>\t\tSomit fungiert Google hier als Auftragsverarbeiter (bzw. externer Anbieter) f\u00fcr diese Website, das heisst, dass Google im Auftrag dieser Website arbeiten, diese Daten sammeln und f\u00fcr diese Website diese Daten analysieren darf.<\/p>\n<p>\t\tGoogle wird diese Informationen benutzen, um deine Nutzung dieser Website auszuwerten, um Reports \u00fcber die Webseiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dieser Website zu erbringen. Die im Rahmen von Google Analytics von deinem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"google-fonts\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">15. | Fonts<\/h3>\n<p>Diese Website setzt zur visuellen Darstellung von Texten und Schriftarten gegebenenfalls den Service Google Fonts und\/oder Adobe Fonts ein. Haupts\u00e4chlich werden aber Schriftarten verwendet, die sich bereits auf diesem Server befinden.<\/p>\n<div class=\"blank50\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Google Fonts<\/h4>\n<p>Falls zur visuellen Darstellung von Texten und Schriftarten der Service von Google Fonts eingesetzt werden sollte, gilt das Folgende:<\/p>\n<p>\t\tDiese Website nutzt den Service von Google Fonts, der zur Verf\u00fcgung gestellt wird (nachfolgend \u00abGoogle\u00bb genannt) von:<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tUm die Darstellung bestimmter Schriften auf dieser Website zu erm\u00f6glichen, wird bei Aufruf dieses Internetauftritts eine Verbindung zu einem Server von Google in den U.S.A. aufgebaut.<\/p>\n<p>\t\tRechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse dieser Website liegt in der Optimierung und dem wirtschaftlichen Betrieb dieses Internetauftritts.<\/p>\n<p>\t\tDurch die bei Aufruf dieser Website hergestellte Verbindung zu Google, kann Google ermitteln, von welcher Webseite die Anfrage gesendet worden ist und an welche IP-Adresse die Darstellung der Schrift zu \u00fcbermitteln ist.<\/p>\n<p>\t\tWeitere Informationen zu Google Web Fonts findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\">https:\/\/developers.google.com\/fonts\/faq<\/a> und in der Datenschutzerkl\u00e4rung von Google: <a class=\"aex-imprint-links\" href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\">https:\/\/www.google.com\/policies\/privacy\/<\/a>.<\/p>\n<div class=\"blank100\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Adobe Fonts<\/h4>\n<p>Diese Website setzt gegebenfalls Typekit-Webschriftarten von Adobe Fonts zur visuellen Gestaltung ein. Adobe Fonts ist ein Dienst von (nachfolgend \u00abAdobe\u00bb genannt):<\/p>\n<p>\t\tAdobe Systems Software Ireland Companies<br \/>\n\t\t4-6 Riverwalk<br \/>\n\t\tCitywest Business Campus<br \/>\n\t\tDublin 24<br \/>\n\t\tIrland<br \/>\n\t\tEurop\u00e4ische Union<\/p>\n<p>\t\tAdobe gew\u00e4hrt dieser Website den Zugriff auf eine Schriftartenbibliothek. Zur Einbindung der von dieser Website benutzten Schriftarten muss dein Browser eine Verbindung zu einem Server von Adobe in den U.S.A. aufbauen und die f\u00fcr diese Website ben\u00f6tigte Schriftart herunterladen. Adobe erh\u00e4lt hierdurch die Information, dass von deiner IP-Adresse diese Website aufgerufen wurde.<\/p>\n<p>\t\tWeitere Informationen zu Adobe Fonts findest du in den Datenschutzhinweisen von Adobe Fonts, die du hier abrufen kannst: <a class=\"aex-imprint-links\" href=\"https:\/\/www.adobe.com\/de\/privacy\/policies\/adobe-fonts.html\" target=\"_blank\">https:\/\/www.adobe.com\/de\/privacy\/policies\/adobe-fonts.html<\/a><\/p>\n<p>\t\tWenn dein Browser Web Fonts nicht unterst\u00fctzt oder du deine Einwilligung nicht erteilst, wird eine Standardschrift von deinem Computer oder deinem mobilen Ednger\u00e4t genutzt.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"google-maps\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">16. | Google Maps<\/h3>\n<p>Diese Website setzt Google Maps zur Darstellung des Standorts sowie zur Erstellung einer Anfahrtsbeschreibung ein. Es handelt sich hierbei um einen Dienst von Google (nachfolgende \u00abGoogle\u00bb genannt).<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tSofern du die in diesen Seiten eingebundene Komponente Google Maps aufrufst, speichert Google \u00fcber deinen Browser ein Cookie auf deinem Endger\u00e4t. Um einen Standort anzuzeigen und eine Anfahrtsbeschreibung zu erstellen, werden deine Nutzereinstellungen und -daten verarbeitet. Hierbei kann diese Website nicht ausschliessen, dass Google Server in den U.S.A. einsetzt.<\/p>\n<p>\t\tRechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse dieser Website liegt in der Optimierung der Funktionalit\u00e4t dieses Internetauftritts.<\/p>\n<p>\t\tDurch die so hergestellte Verbindung zu Google kann Google ermitteln, von welcher Webseite deine Anfrage gesendet worden ist und an welche IP-Adresse die Anfahrtsbeschreibung zu \u00fcbermitteln ist.<\/p>\n<p>\t\tSofern du mit dieser Verarbeitung nicht einverstanden bist, hast du die M\u00f6glichkeit, die Installation bzw. das Setzen von Cookies durch die entsprechenden Einstellungen in deinem Browser zu verhindern. Einzelheiten hierzu findest du vorstehend unter dem Punkt \u00abCookies\u00bb.<\/p>\n<p>\t\tZudem erfolgt die Nutzung von Google Maps sowie der \u00fcber Google Maps erlangten Informationen nach den Google-Nutzungsbedingungen <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/terms?gl=DE&#038;hl=de\" target=\"_blank\">https:\/\/policies.google.com\/terms?gl=DE&#038;hl=de<\/a> und den Gesch\u00e4ftsbedingungen f\u00fcr Google Maps <a class=\"aex-imprint-links\" href=\"https:\/\/google.com\/intl\/de_de\/help\/terms_maps.html\" target=\"_blank\">https:\/\/google.com\/intl\/de_de\/help\/terms_maps.html<\/a>.<\/p>\n<p>\t\t\u00dcberdies bietet Google unter <a class=\"aex-imprint-links\" href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\">https:\/\/adssettings.google.com\/authenticated<\/a> und <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a> weitergehende Informationen an.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"google-recaptcha\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">17. | Google ReCaptcha<\/h3>\n<p>Diese Website setzt Google reCaptcha zur \u00dcberpr\u00fcfung und Vermeidung von Interaktionen durch automatisierte Zugriffe, beispielsweise durch sogenannte Bots, ein. Es handelt sich hierbei um einen Dienst von Google (nachfolgend \u00abGoogle\u00bb genannt).<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDurch diesen Dienst kann Google ermitteln, von welcher Webseite eine Anfrage gesendet wird und von welcher IP-Adresse aus du die sogenannte reCaptcha-Eingabebox verwendest. Neben deiner IP-Adresse werden wom\u00f6glich noch weitere Informationen durch Google erfasst, die f\u00fcr das Angebot und die Gew\u00e4hrleistung dieses Dienstes notwendig sind.<\/p>\n<p>\t\tRechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse dieser Website liegt in der Sicherheit dieses Internetauftritts sowie in der Abwehr unerw\u00fcnschter, automatisierter Zugriffe in Form von Spam und \u00e4hnlichem.<\/p>\n<p>\t\tGoogle bietet unter <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a> weitergehende Informationen zum allgemeinen Umgang mit deinen Nutzerdaten an.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"google-remarketing\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">18. | Google Remarketing,<br \/>\n\t\tGoogle Doubleclick oder<br \/>\n\t\t\u00ab\u00c4hnliche Zielgruppen\u00bb-Komponente von Google<\/h3>\n<p>Diese Website nutzt die Dienste von Google Remarketing, Google Doubleclick oder \u00ab\u00c4hnliche Zielgruppen\u00bb-Komponenten von Google.<\/p>\n<p>\t\tAuf dieser Website kommt die Remarketing- oder \u00ab\u00c4hnliche Zielgruppen\u00bb-Funktion zum Einsatz. Es handelt sich hierbei um einen Dienst der Google LLC (nachfolgend \u00abGoogle\u00bb genannt).<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDiese Website nutzt diese Funktion, um interessenbezogene, personalisierte Werbung auf Internetseiten Dritter, die ebenfalls an dem Werbenetzwerk von Google teilnehmen, zu schalten.<\/p>\n<p>\t\tRechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse dieser Website liegt in der Analyse, Optimierung und dem wirtschaftlichen Betrieb dieses Internetauftritts.<\/p>\n<p>\t\tDamit dieser Werbedienst erm\u00f6glicht werden kann, speichert Google w\u00e4hrend deines Besuchs dieser Website \u00fcber deinen Browser ein Cookie mit einer Zahlenfolge auf deinem Endger\u00e4t. Dieses Cookie erfasst in anonymisierter Form sowohl deinen Besuch als auch die Nutzung dieses Internetauftritts. Personenbezogene Daten werden dabei allerdings nicht weitergegeben. Sofern du anschliessend den Internetauftritt eines Dritten besuchst, der seinerseits ebenfalls das Werbenetzwerk von Google nutzt, werden wom\u00f6glich Werbeeinblendungen erscheinen, die einen Bezug zu diesem Internetauftritt bzw. zu dem dortigen Angeboten von dieser Website aufweisen.<\/p>\n<p>\t\tZur dauerhaften Deaktivierung dieser Funktion bietet Google f\u00fcr die g\u00e4ngigsten Browser \u00fcber <a class=\"aex-imprint-links\" href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\">https:\/\/tools.google.com\/dlpage\/gaoptout<\/a> ein Browser-Plugin an.<\/p>\n<p>\t\tEbenfalls kann die Verwendung von Cookies bestimmter Anbieter beispielsweise \u00fcber <a class=\"aex-imprint-links\" href=\"http:\/\/www.youronlinechoices.com\/uk\/your-ad-choices\" target=\"_blank\">http:\/\/www.youronlinechoices.com\/uk\/your-ad-choices<\/a> oder <a class=\"aex-imprint-links\" href=\"http:\/\/www.networkadvertising.org\/choices\/\" target=\"_blank\">http:\/\/www.networkadvertising.org\/choices\/<\/a> per Opt-Out deaktiviert werden.<\/p>\n<p>\t\tDurch das sogenannte Cross-Device-Marketing kann Google dein Nutzungsverhalten unter Umst\u00e4nden auch \u00fcber mehrere Endger\u00e4te hinweg verfolgen, so dass dir wom\u00f6glich selbst dann interessenbezogene, personalisierte Werbung angezeigt wird, wenn du das Endger\u00e4t wechselst. Dies setzt allerdings voraus, dass du der Verkn\u00fcpfung deiner Browserverl\u00e4ufe mit deinem bestehenden Google-Konto zugestimmt hast.<\/p>\n<p>\t\tGoogle bietet weitergehende Informationen zu Google Remarketing unter <a class=\"aex-imprint-links\" href=\"http:\/\/www.google.com\/privacy\/ads\/\" target=\"_blank\">http:\/\/www.google.com\/privacy\/ads\/<\/a> an. Des Weiteren kannst du weitere Informationen \u00fcber die Datenverarbeitung durch Google den Google-Datenschutzhinweisen entnehmen: <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a>. Dort kannst du im Datenschutzcenter auch deine pers\u00f6nlichen Datenschutz-Einstellungen ver\u00e4ndern.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"youtube\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">19. | YouTube<\/h3>\n<p>Diese Website nutzt die Dienste des Videoportals YouTube (nachfolgend \u00abYouTube\u00bb genannt).<\/p>\n<p>\t\tYouTube LLC.<br \/>\n\t\t901 Cherry Avenue<br \/>\n\t\tSan Bruno<br \/>\n\t\tCalifornia 94066<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tYouTube ist ein Tochterunternehmen von Alphabet, Google LLC. (nachfolgend \u00abGoogle\u00bb genannt).<\/p>\n<p>\t\tAlphabet<br \/>\n\t\tGoogle LLC.<br \/>\n\t\t1600 Amphitheatre Parkway<br \/>\n\t\tMountain View<br \/>\n\t\tCalifornia 94043<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tDiese Website nutzt YouTube im Zusammenhang mit der Funktion \u00abErweiterter Datenschutzmodus\u00bb, um dir Videos anzeigen zu k\u00f6nnen. Rechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse dieser Website liegt in der Qualit\u00e4tsverbesserung dieses Internetauftritts. Die Funktion \u00abErweiterter Datenschutzmodus\u00bb bewirkt laut Angaben von YouTube, dass die nachfolgend noch n\u00e4her bezeichneten Daten nur dann an den Server von YouTube \u00fcbermittelt werden, wenn du ein Video auch tats\u00e4chlich startest.<\/p>\n<p>\t\tWird ein YouTube-Video gestartet, setzt der Anbieter Cookies ein, die Hinweise \u00fcber das Nutzerverhalten sammeln.<\/p>\n<p>\t\tOhne diesen \u00abErweiterten Datenschutz\u00bb wird eine Verbindung zum Server von YouTube in den U.S.A. hergestellt, sobald du eine Seite, auf der ein YouTube-Video eingebettet ist, aufrufst.<\/p>\n<p>\t\tDiese Verbindung ist erforderlich, um das jeweilige Video auf diesen Seiten \u00fcber deinen Browser darstellen zu k\u00f6nnen. Im Zuge dessen wird YouTube zumindest deine IP-Adresse, das Datum mit Uhrzeit und die von dir besuchten Internetseiten erfasst und verarbeitet. Zudem wird eine Verbindung zu dem Werbenetzwerk \u00abDoubleClick\u00bb von Google hergestellt.<\/p>\n<p>\t\tSolltest du gleichzeitig bei YouTube eingeloggt sein (also \u00fcber ein vorhandenes registriertes You-Tube- bzw. Google-Konto haben), weist YouTube die Verbindungsinformationen deinem YouTube-Konto zu. Wenn du das verhindern m\u00f6chtest, musst du dich entweder vor dem Besuch dieser Website bei YouTube (bzw. Google) ausloggen oder die entsprechenden Einstellungen in deinem YouTube-Benutzerkonto vornehmen.<\/p>\n<p>\t\tZum Zwecke der Funktionalit\u00e4t sowie zur Analyse des Nutzungsverhaltens speichert YouTube dauerhaft Cookies \u00fcber deinen Browser auf deinem Endger\u00e4t. Falls du mit dieser Verarbeitung nicht einverstanden bist, hast du M\u00f6glichkeit, die Speicherung der Cookies durch eine Einstellung in deinem Browser zu verhindern. N\u00e4here Informationen hierzu findest du vorstehend unter dem Punkt \u00abCookies\u00bb.<\/p>\n<p>\t\tWeitergehende Informationen \u00fcber die Erhebung und Nutzung von Daten sowie deiner diesbez\u00fcglichen Rechte und Schutzm\u00f6glichkeiten h\u00e4lt Google in den unter <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a> abrufbaren Datenschutzhinweisen bereit.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"social-media\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">20. | Social Media<\/h3>\n<p>Diese Website ist ebenfalls auf diversen Social Media-Kan\u00e4len vertreten, um mit seinen Fans, Followern, Interessenten, Nutzern und Kunden aktiv zu kommunizieren und sie dort \u00fcber Neuigkeiten, Leistungen und Angebote zu informieren.<\/p>\n<p>\t\t\u00abAexraex | The Pioneer\u00bb bzw. \u00abMen of Wrestling\u00bb m\u00f6chten dabei betonen, dass sie als Anbieter keinen Einfluss darauf haben, wie diverse Social Networks Daten verarbeiten. Das heisst, wenn du als Nutzer die Kan\u00e4le dieses Kunstprojekts in den sozialen Medien besuchst, musst du dich bei datenschutzrelevanten Themen bitte jeweils an das Social Network wenden.   <\/p>\n<p>\t\tDiese Website weist dich darauf hin, dass dabei Daten der Nutzer ausserhalb des Raumes der Europ\u00e4ischen Union verarbeitet werden k\u00f6nnen. Hierdurch k\u00f6nnen sich f\u00fcr die Nutzer Risiken ergeben, weil so beispielsweise die Durchsetzung der Rechte der Nutzer erschwert werden k\u00f6nnte.<\/p>\n<p>\t\tFerner werden die Daten der Nutzer von Social Networks im Regelfall f\u00fcr Marktforschungs- und Werbezwecke verarbeitet. So k\u00f6nnen zum Beispiel aus dem Nutzungsverhalten und sich daraus ergebenden Interessen der Nutzer Nutzungsprofile erstellt werden. Die Nutzungsprofile k\u00f6nnen wiederum verwendet werden, um beispielsweise Werbeanzeigen innerhalb und ausserhalb der Plattformen zu schalten, die mutmasslich den Interessen der Nutzer entsprechen. Zu diesen Zwecken werden im Regelfall Cookies auf den Rechnern der Nutzer gespeichert, in denen das Nutzungsverhalten und die Interessen der Nutzer gespeichert werden. Ferner k\u00f6nnen in den Nutzungsprofilen auch Daten unabh\u00e4ngig der von den Nutzern verwendeten Ger\u00e4te gespeichert werden (insbesondere wenn die Nutzer Mitglieder der jeweiligen Plattformen sind und bei diesen eingeloggt sind).<\/p>\n<p>\t\tDie Verarbeitung der personenbezogenen Daten der Nutzer erfolgt auf Grundlage eines berechtigten Interesses dieser Website an einer effektiven Information der Nutzer und Kommunikation mit den Nutzern gem\u00e4ss Artikel 6 Absatz 1 lit. f.) DSGVO. Falls die Nutzer von den jeweiligen Anbietern um eine Einwilligung in die Datenverarbeitung gebeten werden (das heisst ihr Einverst\u00e4ndnis zum Beispiel \u00fcber das Anhaken eines Kontrollk\u00e4stchens oder Best\u00e4tigung einer Schaltfl\u00e4che erkl\u00e4ren) ist die Rechtsgrundlage der Verarbeitung Artikel 6 Absatz 1 lit. a.) und Artikel 7 DSGVO.<\/p>\n<p>\t\tF\u00fcr eine detaillierte Darstellung der jeweiligen Verarbeitungen und der Widerspruchsm\u00f6glichkeiten (Opt-Out), verweist diese Website auf die nachfolgend verlinkten Angaben der Anbieter.<\/p>\n<p>\t\tAuch im Fall von Auskunftsanfragen und der Geltendmachung von Nutzerrechten, weist diese Website darauf hin, dass diese am effektivsten bei den Anbietern geltend gemacht werden k\u00f6nnen. Nur die Anbieter haben jeweils Zugriff auf die Daten der Nutzer und k\u00f6nnen direkt entsprechende Massnahmen ergreifen und Ausk\u00fcnfte geben.<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">GOOGLE<\/p>\n<p>\t\t\t\t\tAlphabet<br \/>\n\t\t\t\t\tGoogle LLC<br \/>\n\t\t\t\t\t1600 Amphitheatre Parkway<br \/>\n\t\t\t\t\tMountain View<br \/>\n\t\t\t\t\tCalifornia 94043<br \/>\n\t\t\t\t\tU.S.A.<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen bez\u00fcglich Google findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a>, \u00fcber das Opt-Out unter <a class=\"aex-imprint-links\" href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\">https:\/\/adssettings.google.com\/authenticated<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">FACEBOOK<\/p>\n<p>\t\t\t\t\tMeta<br \/>\n\t\t\t\t\tFacebook Ireland Ltd.<br \/>\n\t\t\t\t\t4 Grand Canal Square<br \/>\n\t\t\t\t\tGrand Canal Harbour<br \/>\n\t\t\t\t\tDublin 2<br \/>\n\t\t\t\t\tIrland<br \/>\n\t\t\t\t\tEurop\u00e4ische Union<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen bez\u00fcglich Facebook findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/facebook.com\/about\/privacy\/\" target=\"_blank\">https:\/\/facebook.com\/about\/privacy\/<\/a>, \u00fcber das Opt-Out unter <a class=\"aex-imprint-links\" href=\"https:\/\/facebook.com\/settings?tab=ads\" target=\"_blank\">https:\/\/facebook.com\/settings?tab=ads<\/a> und <a class=\"aex-imprint-links\" href=\"https:\/\/www.youronlinechoices.com\" target=\"_blank\">https:\/\/www.youronlinechoices.com<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">LINKEDIN<\/p>\n<p>\t\t\t\t\tLinkedIn Ireland Unlimited Company<br \/>\n\t\t\t\t\tWilton Place<br \/>\n\t\t\t\t\tDublin 2<br \/>\n\t\t\t\t\tIrland<br \/>\n\t\t\t\t\tEurop\u00e4ische Union<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen bez\u00fcglich LinkedIn findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/linkedin.com\/legal\/privacy-policy\" target=\"_blank\">https:\/\/linkedin.com\/legal\/privacy-policy<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">PINTEREST<\/p>\n<p>\t\t\t\t\tPinterest Inc.<br \/>\n\t\t\t\t\t635 High Street<br \/>\n\t\t\t\t\tPalo Alto<br \/>\n\t\t\t\t\tCalifornia 94301<br \/>\n\t\t\t\t\tU.S.A.<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen und \u00fcber das Opt-Out bez\u00fcglich Pinterest findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/policy.pinterest.com\/de\/privacy-policy\" target=\"_blank\">https:\/\/policy.pinterest.com\/de\/privacy-policy<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">SOUNDCLOUD<\/p>\n<p>\t\t\t\t\tSoundCloud Limited<br \/>\n\t\t\t\t\tRheinsberger Strasse 76\/77<br \/>\n\t\t\t\t\t10115 Berlin<br \/>\n\t\t\t\t\tDeutschland<br \/>\n\t\t\t\t\tEurop\u00e4ische Union<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen und \u00fcber das Opt-Out bez\u00fcglich SoundCloud findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/soundcloud.com\/pages\/privacy\" target=\"_blank\">https:\/\/soundcloud.com\/pages\/privacy<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">VIMEO<\/p>\n<p>\t\t\t\t\tVimeo LLC<br \/>\n\t\t\t\t\t555 West 18th Street<br \/>\n\t\t\t\t\tNew York<br \/>\n\t\t\t\t\tNew York 10011<br \/>\n\t\t\t\t\tU.S.A.<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen bez\u00fcglich Vimeo findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\">https:\/\/vimeo.com\/privacy<\/a> und \u00fcber das Opt-Out unter <a class=\"aex-imprint-links\" href=\"https:\/\/vimeo.com\/cookie_policy\" target=\"_blank\">https:\/\/vimeo.com\/cookie_policy<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">XING<\/p>\n<p>\t\t\t\t\tXing AG<br \/>\n\t\t\t\t\tDammtorstrasse 29-32<br \/>\n\t\t\t\t\t20354 Hamburg<br \/>\n\t\t\t\t\tDeutschland<br \/>\n\t\t\t\t\tEurop\u00e4ische Union<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen und \u00fcber das Opt-Out bez\u00fcglich Xing findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/privacy.xing.com\/de\/datenschutzerklaerung\" target=\"_blank\">https:\/\/privacy.xing.com\/de\/datenschutzerklaerung<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imrpint\" id=\"social-plugins\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">21. | Social Plugins<\/h3>\n<p>Social-Plugins verbinden Websites mit sozialen Netzwerken wie Facebook, Twitter etc.. Die meisten Social-Plugins werden in Webseiten integriert, um Social-Media-Kan\u00e4le zu erschliessen und die Anzahl der Besucher zu erh\u00f6hen oder Besucher langfristig zu binden. Nur leider k\u00f6nnen die Anbieter dieser sozialen Netzwerke durch diese Social-Plugins deinen Besuch von Websites entweder direkt oder indirekt tracken.<\/p>\n<p>\t\tUm deine Privatsph\u00e4re zu sch\u00fctzen, setzt diese Website keine Social-Plugins von sozialen Netzwerken ein! Bitte lese dir diesbez\u00fcglich den n\u00e4chsten Abschnitt \u00ab<a class=\"aex-imprint-links\" href=\"#shariff\" target=\"_self\">Datenschutzkonforme Social Media-Buttons: \u00abShariff\u00bb-Buttons<\/a>\u00bb durch.<\/p>\n<div class=\"blank50\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Social-Plugins von Facebook<\/h4>\n<p>Diese Website m\u00f6chte besonders betonen, dass auf diesen Seiten keine Social-Plugins von Facebook (\u00abGef\u00e4llt mir\u00bb- oder \u00abTeilen\u00bb-Buttons) implementiert sind, damit deine Besuche dieser Website seitens Facebook (gleichg\u00fcltig ob du ein Account bei Facebook hast oder nicht), nicht direkt oder indirekt mittels dieser Social-Plugins getrackt werden k\u00f6nnen!<\/p>\n<div class=\"blank50\"><\/div>\n<h4 data-aos=\"flip-right\" data-aos-duration=\"1800\">Social-Plugins von Twitter<\/h4>\n<p>Diese Website m\u00f6chte weiterhin besonders betonen, dass auf diesen Seiten keine Social-Plugins von Twitter (\u00abTweet\u00bb- oder \u00abReTweet\u00bb-Buttons) implementiert sind. \u00abMen of Wrestling\u00bb nimmt die Dienste von Twitter nicht in Anspruch.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"shariff\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">22. | Datenschutzkonforme Social Media-Buttons: \u00abShariff\u00bb-Buttons\u00bb<\/h3>\n<p>Diese Website setzt unter Umst\u00e4nden Plugins der nachfolgend genannten Social Networks ein. Zur Einbindung dieser Plugins nutzt diese Website wiederum das datenschutzkonforme Plugin \u00abShariff\u00bb ein.<\/p>\n<p>\t\tRechtsgrundlage ist Artikel 6 Absatz 1 lit. f.) DSGVO. Das berechtigte Interesse liegt in der Qualit\u00e4tsverbesserung des Internetauftritts dieses Projekts.<\/p>\n<p>\t\tShariff ist ein Open-Source-Programm, das von \u00abc\u2019t\u00bb und \u00abheise\u00bb entwickelt worden ist. Durch die Einbindung dieses Plugins wird im Wege verlinkter Grafiken verhindert, dass die nachfolgend n\u00e4her benannten Social Network-Plugins bei deinem Besuch dieser Seiten, auf denen wiederum das jeweilige Social Network-Plugin eingebunden ist, automatisch eine Verbindung zu dem jeweiligen Server des Social Network-Plugins herstellt. Erst wenn du auf eine dieser verlinkten Grafiken klickst, wirst du zu dem Dienst des jeweiligen Social Networks weitergeleitet. Auch erst dann werden durch das jeweilige Social Network Informationen \u00fcber den Nutzungsvorgang erfasst. Zu diesen Informationen z\u00e4hlen beispielsweise deine IP-Adresse, das Datum und die Uhrzeit sowie die von dir besuchten Seiten dieses Projekts.<\/p>\n<p>\t\tSolltest du bei einem der Social Network-Dienste eingeloggt sein, w\u00e4hrend du eine mit dem damit korrespondieren Plugin versehenen Internetseite besuchst, kann der Anbieter des jeweiligen Social Networks (beispielsweise Facebook etc.) wom\u00f6glich die so gesammelten Informationen deines konkreten Besuchs erkennen und deinem pers\u00f6nlichen Nutzerkonto zuordnen bzw. hier\u00fcber ver\u00f6ffentlichen. Sofern du also beispielsweise den sogenannten \u00abLike\u00bb oder \u00abTeilen\u00bb-Button des jeweiligen Social Networks benutzt, werden diese Informationen gegebenenfalls in deinem dortigen Nutzerkonto gespeichert und \u00fcber die Plattform des jeweiligen Social Network-Anbieters ver\u00f6ffentlicht. Wenn du das verhindern m\u00f6chtest, musst du dich entweder vor dem Klick auf die Grafik bei dem jeweiligen Social Network ausloggen oder die entsprechenden Einstellungen in deinem Benutzerkonto des Social Networks vornehmen.<\/p>\n<p>\t\tWeitergehende Informationen \u00fcber \u00abShariff\u00bb h\u00e4lt der Anbieter \u00abheise\u00bb unter <a class=\"aex-imprint-links\" href=\"https:\/\/www.heise.de\/ct\/artikel\/Shariff-Social-Media-Buttons-mit-Datenschutz-2467514.html\" target=\"_blank\">https:\/\/www.heise.de\/ct\/artikel\/Shariff-Social-Media-Buttons-mit-Datenschutz-2467514.html<\/a> bereit.<\/p>\n<p>\t\tFolgende Social Networks sind (unter Umst\u00e4nden) auf dieser Website eingebunden:<\/p>\n<div class=\"blank10\"><\/div>\n<div class=\"aex-imprint-table\">\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">GOOGLE<\/p>\n<p>\t\t\t\t\tAlphabet<br \/>\n\t\t\t\t\tGoogle LLC<br \/>\n\t\t\t\t\t1600 Amphitheatre Parkway<br \/>\n\t\t\t\t\tMountain View<br \/>\n\t\t\t\t\tCalifornia 94043<br \/>\n\t\t\t\t\tU.S.A..<\/p>\n<p>\t\t\t\t\tDatenschutzinformationen bez\u00fcglich Google findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"aex-imprint-table-sub\">\n<div class=\"aex-imprint-table-sub-left\">&bull;<\/div>\n<div class=\"aex-imprint-table-sub-right\">FACEBOOK<\/p>\n<p>\t\t\t\t\tMeta<br \/>\n\t\t\t\t\tFacebook Inc.<br \/>\n\t\t\t\t\t1601 South California Avenue<br \/>\n\t\t\t\t\tPalo Alto<br \/>\n\t\t\t\t\tCalifornia 94304<br \/>\n\t\t\t\t\tU.S.A.<\/p>\n<p>\t\t\t\t\tFacebook Inc. wird innerhalb der Europ\u00e4ischen Union betrieben durch<\/p>\n<p>\t\t\t\t\tMeta<br \/>\n\t\t\t\t\tFacebook Ireland Limited<br \/>\n\t\t\t\t\t4 Grand Canal Square<br \/>\n\t\t\t\t\tDublin 2<br \/>\n\t\t\t\t\tIrland<br \/>\n\t\t\t\t\tEurop\u00e4ische UnionDatenschutzinformationen bez\u00fcglich Facebook findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/facebook.com\/policy.php\" target=\"_blank\">https:\/\/facebook.com\/policy.php<\/a>.\n\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"likes\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">23. | Die \u00abLike\u00bb-Funktion<\/h3>\n<p>Innerhalb dieser Website k\u00f6nnen (unter Umst\u00e4nden) \u00abLike\u00bb-Buttons implemtiert sein, also sogenannte \u00abGef\u00e4llt mir\u00bb-Buttons, mit denen du beim Klicken auf einen dieser Buttons zum Ausdruck bringen kannst, dass dir beispielsweise ein bestimmter Inhalt, ein Bild oder \u00e4hnliches gef\u00e4llt.<\/p>\n<p>\t\tDiese Website m\u00f6chte betonen, dass diese \u00abLike\u00bb-Buttons nicht Facebook, Twitter etc. zugeh\u00f6rig sind!<\/p>\n<p>\t\tDiese \u00abLike\u00bb-Buttons sind ein elementarer Teil des Systems dieses Projekts und diese Daten werden an niemanden weitergeleitet und verbleiben im System dieser Website.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"sweepstakes\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">24. | Gewinnspiele<\/h3>\n<p>\u00abMen of Wrestling\u00bb kann in seinen Social Media-Kan\u00e4len oder auch direkt auf dieser Website Gewinnspiele anbieten, um auf sein Kunstprojekt aufmerksam zu machen. Sofern du an einem dieser Gewinnspiele teilnimmst, werden die von dir anl\u00e4sslich der Teilnahme eingegebenen Daten ohne deine weitergehende Einwilligung, aber nat\u00fcrlich ausschliesslich nur zur Durchf\u00fchrung und Abwicklung des jeweiligen Gewinnspiels, verarbeitet.<\/p>\n<p>\t\tIm Rahmen der Abwicklung des Gewinnspiels gibt diese Website deine Daten an das mit der Warenlieferung beauftragte Transportunternehmen oder an einen Finanzdienstleister weiter, soweit die Weitergabe zur Lieferung bzw. Auszahlung deines Gewinns erforderlich ist. Sofern deine Daten im Falle eines Gewinns ver\u00f6ffentlicht werden, wirst du hierauf im Rahmen der Einwilligungserkl\u00e4rung hingewiesen.<\/p>\n<p>\t\tRechtsgrundlage f\u00fcr die Weitergabe der Daten ist dann Artikel 6 Absatz 1 lit. b.) DSGVO.<\/p>\n<p>\t\tDeine Einwilligung in die Verarbeitung der Daten zur Teilnahme an den Gewinnspielen kannst du gem\u00e4ss Artikel 7 Absatz 3 DSGVO jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Hierzu musst du den Betreiber dieser Website lediglich \u00fcber deinen Widerruf in Kenntnis setzen.<\/p>\n<\/p><\/div>\n<div class=\"blank150\"><\/div>\n<div class=\"blank50-imprint\" id=\"cloudfare\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">25. | Cloudfare<\/h3>\n<p>\u00abMen of Wrestling\u00bb nimmt die Dienste des Content Delivery Dienstes (CDN) von Cloudfare Inc. (nachfolgend \u00abCloudfare\u00bb genannt) in Anspruch.<\/p>\n<p>\t\tCloudfare Inc.<br \/>\n\t\t101 Townsend Street<br \/>\n\t\tSan Francisco<br \/>\n\t\tCA 94107<br \/>\n\t\tU.S.A.<\/p>\n<p>\t\tEin Content Delivery Network ist ein Dienst, mit dessen Hilfe Inhalte dieser Website bzw. dieser Community, insbesondere grosse Mediendateien, wie Grafiken oder Skripte mit Hilfe regional verteilter und \u00fcber das Internet verbundener Server, schneller ausgeliefert werden. Die Verarbeitung der Daten der Nutzer erfolgt alleine zu den vorgenannten Zwecken und der Aufrechterhaltung der Sicherheit und Funktionsf\u00e4higkeit des CDN.<\/p>\n<p>\t\tDie Nutzung erfolgt auf Grundlage eines berechtigten Interesses dieser Website, das heisst, dass diese Website das Interesse an einer sicheren und effizienten Bereitstellung, Analyse sowie Optimierung der Community gem\u00e4ss Artikel 6 Absatz 1 lit. f.) der Datenschutzgrundverordnung hat.<\/p>\n<p>\t\tWeitere Informationen bez\u00fcglich der Datenschutzerkl\u00e4rung von Cloudflare findest du unter <a class=\"aex-imprint-links\" href=\"https:\/\/cloudflare.com\/security-policy\" target=\"_blank\">https:\/\/cloudflare.com\/security-policy<\/a>.<\/p>\n<\/p><\/div>\n<div class=\"blank200\"><\/div>\n<div class=\"aex-box-imprint\">\n<h3 data-aos=\"flip-right\" data-aos-duration=\"1800\">Information<\/h3>\n<p>Letzte Aktualisierung:<br \/>\n\t\tD\u00fcsseldorf, 11. M\u00e4rz 2023<\/p>\n<p class=\"aex-imprint-grey\">Bei Missverst\u00e4ndnissen, \u00dcbersetzungsfehlern oder Ungereimtheiten,<br \/>\n\t\that diese Datenschutzerkl\u00e4rung nur in ihrer deutschen Fassung ihre G\u00fcltigkeit.<\/p>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"es","enabled_languages":["de","tr","en","es","br","fr","it","ar","ru","zh","ko","hi","ja"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":false,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false},"es":{"title":true,"content":false,"excerpt":false},"br":{"title":true,"content":false,"excerpt":false},"fr":{"title":true,"content":false,"excerpt":false},"it":{"title":true,"content":false,"excerpt":false},"ar":{"title":true,"content":false,"excerpt":false},"ru":{"title":true,"content":false,"excerpt":false},"zh":{"title":true,"content":false,"excerpt":false},"ko":{"title":true,"content":false,"excerpt":false},"hi":{"title":true,"content":false,"excerpt":false},"ja":{"title":true,"content":false,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere\" \/>\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/menofwrestling.com\/es\/privacy-policy\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hombres de Lucha Libre | Lucha en Aceite Turca \u2022 T\u00fcrk Ya\u011fl\u0131 Pehlivan G\u00fcre\u015fleri\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad | Hombres de Lucha Libre\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/menofwrestling.com\/es\/privacy-policy\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-08-16T21:57:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-08-18T17:20:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edtica de Privacidad | Hombres de Lucha Libre\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/privacy-policy\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/menofwrestling.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/privacy-policy\\\/#listItem\",\"name\":\"Pol\\u00edtica de Privacidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/privacy-policy\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica de Privacidad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/#person\",\"name\":\"Aexraex\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/privacy-policy\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f247970596d2944ccd72025919f45541c248bd03a5637a3d3586eba569ab1f26?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Aexraex\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/privacy-policy\\\/#webpage\",\"url\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/privacy-policy\\\/\",\"name\":\"Pol\\u00edtica de Privacidad | Hombres de Lucha Libre\",\"description\":\"\\u00abMen of Wrestling | Turkish Oil Wrestling\\u00bb nimmt den Schutz deiner pers\\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \\u00abMen of Wrestling\\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\\u00e4rung informiert dich \\u00abMen of Wrestling\\u00bb insbesondere\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/privacy-policy\\\/#breadcrumblist\"},\"datePublished\":\"2023-08-16T23:57:11+02:00\",\"dateModified\":\"2023-08-18T19:20:20+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/\",\"name\":\"Men of Wrestling | Turkish Oil Wrestling \\u2022 Ya\\u011fl\\u0131 Pehlivan G\\u00fcre\\u015fleri\",\"description\":\"Lucha en Aceite Turca \\u2022 T\\u00fcrk Ya\\u011fl\\u0131 Pehlivan G\\u00fcre\\u015fleri\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/menofwrestling.com\\\/es\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edtica de Privacidad | Hombres de Lucha Libre","description":"\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere","canonical_url":"https:\/\/menofwrestling.com\/es\/privacy-policy\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/menofwrestling.com\/es\/privacy-policy\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/menofwrestling.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/menofwrestling.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/menofwrestling.com\/es\/privacy-policy\/#listItem","name":"Pol\u00edtica de Privacidad"}},{"@type":"ListItem","@id":"https:\/\/menofwrestling.com\/es\/privacy-policy\/#listItem","position":2,"name":"Pol\u00edtica de Privacidad","previousItem":{"@type":"ListItem","@id":"https:\/\/menofwrestling.com\/es#listItem","name":"Home"}}]},{"@type":"Person","@id":"https:\/\/menofwrestling.com\/es\/#person","name":"Aexraex","image":{"@type":"ImageObject","@id":"https:\/\/menofwrestling.com\/es\/privacy-policy\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/f247970596d2944ccd72025919f45541c248bd03a5637a3d3586eba569ab1f26?s=96&d=mm&r=g","width":96,"height":96,"caption":"Aexraex"}},{"@type":"WebPage","@id":"https:\/\/menofwrestling.com\/es\/privacy-policy\/#webpage","url":"https:\/\/menofwrestling.com\/es\/privacy-policy\/","name":"Pol\u00edtica de Privacidad | Hombres de Lucha Libre","description":"\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/menofwrestling.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/menofwrestling.com\/es\/privacy-policy\/#breadcrumblist"},"datePublished":"2023-08-16T23:57:11+02:00","dateModified":"2023-08-18T19:20:20+02:00"},{"@type":"WebSite","@id":"https:\/\/menofwrestling.com\/es\/#website","url":"https:\/\/menofwrestling.com\/es\/","name":"Men of Wrestling | Turkish Oil Wrestling \u2022 Ya\u011fl\u0131 Pehlivan G\u00fcre\u015fleri","description":"Lucha en Aceite Turca \u2022 T\u00fcrk Ya\u011fl\u0131 Pehlivan G\u00fcre\u015fleri","inLanguage":"es-ES","publisher":{"@id":"https:\/\/menofwrestling.com\/es\/#person"}}]},"og:locale":"es_ES","og:site_name":"Hombres de Lucha Libre | Lucha en Aceite Turca \u2022 T\u00fcrk Ya\u011fl\u0131 Pehlivan G\u00fcre\u015fleri","og:type":"article","og:title":"Pol\u00edtica de Privacidad | Hombres de Lucha Libre","og:description":"\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere","og:url":"https:\/\/menofwrestling.com\/es\/privacy-policy\/","article:published_time":"2023-08-16T21:57:11+00:00","article:modified_time":"2023-08-18T17:20:20+00:00","twitter:card":"summary_large_image","twitter:title":"Pol\u00edtica de Privacidad | Hombres de Lucha Libre","twitter:description":"\u00abMen of Wrestling | Turkish Oil Wrestling\u00bb nimmt den Schutz deiner pers\u00f6nlichen Daten sehr ernst. Aus diesem Grund behandelt \u00abMen of Wrestling\u00bb deine personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften, gem\u00e4ss der Datenschutzgrundverordnung (DSGVO) und des California Consumer Privacy Acts (CCPA), sowie dieser Datenschutzerkl\u00e4rung. Mit dieser nachfolgenden Datenschutzerkl\u00e4rung informiert dich \u00abMen of Wrestling\u00bb insbesondere"},"aioseo_meta_data":{"post_id":"3","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":false,"robots_noindex":true,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-08-18 00:05:52","updated":"2025-06-03 22:12:11","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/menofwrestling.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPol\u00edtica de Privacidad\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/menofwrestling.com\/es"},{"label":"Pol\u00edtica de Privacidad","link":"https:\/\/menofwrestling.com\/es\/privacy-policy\/"}],"_links":{"self":[{"href":"https:\/\/menofwrestling.com\/es\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menofwrestling.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/menofwrestling.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/menofwrestling.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/menofwrestling.com\/es\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/menofwrestling.com\/es\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/menofwrestling.com\/es\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}